{"id":40889,"date":"2025-12-16T10:30:00","date_gmt":"2025-12-16T08:30:00","guid":{"rendered":"https:\/\/www.sindicaturabarcelona.cat\/?p=40889"},"modified":"2025-12-18T12:23:37","modified_gmt":"2025-12-18T10:23:37","slug":"la-sindicatura-insta-al-ayuntamiento-a-reforzar-los-servicios-de-atencion-a-las-victimas-de-violencias-sexuales","status":"publish","type":"post","link":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-al-ayuntamiento-a-reforzar-los-servicios-de-atencion-a-las-victimas-de-violencias-sexuales\/","title":{"rendered":"La Sindicatura insta al Ayuntamiento a reforzar los servicios de atenci\u00f3n a las v\u00edctimas de violencias sexuales"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">La entrada en el circuito de atenci\u00f3n para las v\u00edctimas de violencias sexuales no recientes no est\u00e1 clara y puede dar lugar a revictimizaciones secundarias: es necesario disponer de atenci\u00f3n espec\u00edfica para este tipo de violencias, que son las mayoritarias.<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Tambi\u00e9n es necesario aumentar los recursos residenciales de urgencia y de larga estancia, as\u00ed como la estabilidad de los equipos profesionales, ya que existe un grado de rotaci\u00f3n que puede afectar a los servicios.<\/h2>\n\n\n\n<p>La defensor\u00eda de la ciudad publica el informe monogr\u00e1fico \u00ab<a href=\"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/20251217-INF-Violencies.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Los servicios de atenci\u00f3n a las violencias sexuales en la ciudad de Barcelona<\/strong><\/a>\u00ab, en el que han participado m\u00e1s de un centenar de personas que trabajan en servicios sociales y sanitarios y en entidades autogestionadas. As\u00ed mismo, se han analizado protocolos y otros documentos espec\u00edficos, as\u00ed como los 18 servicios especializados que existen en la ciudad.<\/p>\n\n\n\n<p>En los \u00faltimos a\u00f1os, se constata <strong>un gran aumento en las denuncias y revelaciones<\/strong> de situaciones de violencia sexual. Este incremento de casos ha podido impactar en forma de saturaci\u00f3n en los servicios: de acuerdo con la encuesta que se ha llevado a cabo, el tiempo que suele transcurrir desde el primer contacto hasta que comienza la actuaci\u00f3n es muy superior al ideal, con una media de 3,3 meses de espera.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Estancias demasiado largas en recursos de urgencia<\/h2>\n\n\n\n<p>Los datos recogidos muestran que la mayor\u00eda de las personas atendidas por los servicios no han vivido la violencia sexual de forma reciente, sino que ha transcurrido una <strong>media de 3 a\u00f1os desde el incidente violento hasta la llegada al servicio<\/strong>.<\/p>\n\n\n\n<p>Los equipos profesionales indican que las v\u00edctimas suelen haber visitado previamente una media de 2,17 servicios y, en algunos casos, han pasado previamente por m\u00e1s de 10 servicios, lo que puede implicar una victimizaci\u00f3n secundaria importante.<\/p>\n\n\n\n<p>La entrada en el circuito de atenci\u00f3n es m\u00e1s clara para los casos de violencias sexuales recientes. Ahora bien, hay <strong>contradicciones en la informaci\u00f3n municipal<\/strong>: las <a href=\"https:\/\/ajuntament.barcelona.cat\/dones\/es\/guias-del-buen-trato\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Gu\u00edas del buen trato<\/em><\/a> de algunos distritos se\u00f1alan que el Hospital Cl\u00ednic y el de la Vall d&#8217;Hebron son los referentes si la violencia sexual ha ocurrido en las \u00faltimas 72 horas. Sin embargo, en otros distritos estas gu\u00edas no establecen limitaciones temporales.<\/p>\n\n\n\n<p>Adem\u00e1s, <strong>son habituales las estancias demasiado largas en los recursos residenciales<\/strong>, sobre todo en los de urgencia, en los que se llega a quintuplicar las estancias m\u00e1ximas recomendadas. Tambi\u00e9n se ha identificado una carencia de recursos residenciales para mujeres con necesidades espec\u00edficas (con consumo activos de drogas, con problemas graves de salud mental&#8230;).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Personal de los servicios: mucha rotaci\u00f3n y <em>burnout<\/em><\/h2>\n\n\n\n<p><strong>Las condiciones de trabajo de los equipos profesionales son mejorables<\/strong>. Esto se refleja en el \u00edndice de inestabilidad laboral tan elevado: en los servicios de tipo social, la mayor\u00eda de las personas trabajadoras declaran que el equipo cambia cada a\u00f1o o menos, incluso. Algunas personas remarcan tambi\u00e9n la falta de recursos que sufren.<\/p>\n\n\n\n<p>No ha habido un incremento de profesional proporcional al de personas atendidas, lo que redunda en un mayor estr\u00e9s. Los profesionales destacan el impacto emocional, la responsabilidad y <strong>s\u00edntomas de agotamiento profesional (<em>burnout<\/em>)<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Recomendaciones de la Sindicatura de Greuges de Barcelona<\/strong><\/h2>\n\n\n\n<p>Realizado este an\u00e1lisis, la defensor\u00eda ha elaborado varias recomendaciones:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Acordar una definici\u00f3n de violencias sexuales<\/strong>, alineada con la normativa vigente y compartida por todos los recursos.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Establecer una entrada clara en el circuito <\/strong>de servicios para casos de violencias sexuales recientes y no recientes, detallando los servicios disponibles y sus funciones, as\u00ed como los criterios de atenci\u00f3n y los mecanismos de coordinaci\u00f3n y derivaci\u00f3n.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Actualizar las <em>Gu\u00edas del buen trato<\/em> <\/strong>de los distritos para incluir servicios espec\u00edficos y criterios de atenci\u00f3n en violencias sexuales. Otros recursos adecuados ser\u00edan mapas de servicios p\u00fablicos y privados que ofrecen atenci\u00f3n a v\u00edctimas, que deber\u00edan crearse y hacerse despu\u00e9s difusi\u00f3n.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Asegurar una <strong>atenci\u00f3n especializada y adecuada<\/strong> para cada tipo de violencia sexual, asignando m\u00e1s recursos residenciales de urgencia y de larga estancia.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Dotar a los servicios espec\u00edficos de personal y recursos suficientes<\/strong> para poder atender a las personas adecuadamente, asegurando la estabilidad de los equipos profesionales para evitar la alta rotaci\u00f3n del personal, y proporcionarles condiciones laborales que tengan en cuenta la carga elevada de estr\u00e9s emocional que tienen.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Estudiar si es necesario que el Ayuntamiento cree <strong>categor\u00edas profesionales espec\u00edficas<\/strong> que aseguren la especializaci\u00f3n de las personas que atienden a las violencias sexuales.<\/li>\n<\/ul>\n\n\n\n<p>Pod\u00e9is consultar el <a href=\"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/20251217-INF-Violencies.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">informe entero en este enlace<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La entrada en el circuito de atenci\u00f3n para las v\u00edctimas de violencias sexuales no recientes no est\u00e1 clara y puede dar lugar a revictimizaciones secundarias: es necesario disponer de atenci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":40830,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"tags":[],"drets":[1475,1582],"class_list":["post-40889","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","drets-ciudad-equitativa","drets-derecho-a-una-vida-libre-de-violencias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Sindicatura insta al Ayuntamiento a reforzar los servicios de atenci\u00f3n a las v\u00edctimas de violencias sexuales - Sindicatura de Greuges de Barcelona<\/title>\n<meta name=\"description\" content=\"La defensor\u00eda publica un informe que concluye que es necesario disponer de atenci\u00f3n espec\u00edfica para los casos de violencias no recientes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-al-ayuntamiento-a-reforzar-los-servicios-de-atencion-a-las-victimas-de-violencias-sexuales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Sindicatura insta al Ayuntamiento a reforzar los servicios de atenci\u00f3n a las v\u00edctimas de violencias sexuales - Sindicatura de Greuges de Barcelona\" \/>\n<meta property=\"og:description\" content=\"La defensor\u00eda publica un informe que concluye que es necesario disponer de atenci\u00f3n espec\u00edfica para los casos de violencias no recientes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-al-ayuntamiento-a-reforzar-los-servicios-de-atencion-a-las-victimas-de-violencias-sexuales\/\" \/>\n<meta property=\"og:site_name\" content=\"Sindicatura de Greuges de Barcelona\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-16T08:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-18T10:23:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/punt_lila_intinerant_resized_0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"799\" \/>\n\t<meta property=\"og:image:height\" content=\"534\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pablo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sindicbarcelona\" \/>\n<meta name=\"twitter:site\" content=\"@sindicbarcelona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pablo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-insta-al-ayuntamiento-a-reforzar-los-servicios-de-atencion-a-las-victimas-de-violencias-sexuales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-insta-al-ayuntamiento-a-reforzar-los-servicios-de-atencion-a-las-victimas-de-violencias-sexuales\\\/\"},\"author\":{\"name\":\"Pablo\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#\\\/schema\\\/person\\\/0e5acffc350ffdbc97578159322c9452\"},\"headline\":\"La Sindicatura insta al Ayuntamiento a reforzar los servicios de atenci\u00f3n a las v\u00edctimas de violencias sexuales\",\"datePublished\":\"2025-12-16T08:30:00+00:00\",\"dateModified\":\"2025-12-18T10:23:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-insta-al-ayuntamiento-a-reforzar-los-servicios-de-atencion-a-las-victimas-de-violencias-sexuales\\\/\"},\"wordCount\":800,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-insta-al-ayuntamiento-a-reforzar-los-servicios-de-atencion-a-las-victimas-de-violencias-sexuales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/punt_lila_intinerant_resized_0.jpg\",\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-insta-al-ayuntamiento-a-reforzar-los-servicios-de-atencion-a-las-victimas-de-violencias-sexuales\\\/\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-insta-al-ayuntamiento-a-reforzar-los-servicios-de-atencion-a-las-victimas-de-violencias-sexuales\\\/\",\"name\":\"La Sindicatura insta al Ayuntamiento a reforzar los servicios de atenci\u00f3n a las v\u00edctimas de violencias sexuales - Sindicatura de Greuges de Barcelona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-insta-al-ayuntamiento-a-reforzar-los-servicios-de-atencion-a-las-victimas-de-violencias-sexuales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-insta-al-ayuntamiento-a-reforzar-los-servicios-de-atencion-a-las-victimas-de-violencias-sexuales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/punt_lila_intinerant_resized_0.jpg\",\"datePublished\":\"2025-12-16T08:30:00+00:00\",\"dateModified\":\"2025-12-18T10:23:37+00:00\",\"description\":\"La defensor\u00eda publica un informe que concluye que es necesario disponer de atenci\u00f3n espec\u00edfica para los casos de violencias no recientes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-insta-al-ayuntamiento-a-reforzar-los-servicios-de-atencion-a-las-victimas-de-violencias-sexuales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-insta-al-ayuntamiento-a-reforzar-los-servicios-de-atencion-a-las-victimas-de-violencias-sexuales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-insta-al-ayuntamiento-a-reforzar-los-servicios-de-atencion-a-las-victimas-de-violencias-sexuales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/punt_lila_intinerant_resized_0.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/punt_lila_intinerant_resized_0.jpg\",\"width\":799,\"height\":534},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-insta-al-ayuntamiento-a-reforzar-los-servicios-de-atencion-a-las-victimas-de-violencias-sexuales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Sindicatura insta al Ayuntamiento a reforzar los servicios de atenci\u00f3n a las v\u00edctimas de violencias sexuales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/\",\"name\":\"Sindicatura de Greuges de Barcelona\",\"description\":\"La defensoria dels teus drets\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#organization\",\"name\":\"Sindicatura de Greuges de Barcelona\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/logo_sindicatura.svg\",\"contentUrl\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/logo_sindicatura.svg\",\"caption\":\"Sindicatura de Greuges de Barcelona\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/sindicbarcelona\",\"https:\\\/\\\/www.instagram.com\\\/sindicbarcelona\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@sindicaturabcn\",\"https:\\\/\\\/t.me\\\/sindicaturabarcelona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#\\\/schema\\\/person\\\/0e5acffc350ffdbc97578159322c9452\",\"name\":\"Pablo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g\",\"caption\":\"Pablo\"},\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/author\\\/pablo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Sindicatura insta al Ayuntamiento a reforzar los servicios de atenci\u00f3n a las v\u00edctimas de violencias sexuales - Sindicatura de Greuges de Barcelona","description":"La defensor\u00eda publica un informe que concluye que es necesario disponer de atenci\u00f3n espec\u00edfica para los casos de violencias no recientes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-al-ayuntamiento-a-reforzar-los-servicios-de-atencion-a-las-victimas-de-violencias-sexuales\/","og_locale":"es_ES","og_type":"article","og_title":"La Sindicatura insta al Ayuntamiento a reforzar los servicios de atenci\u00f3n a las v\u00edctimas de violencias sexuales - Sindicatura de Greuges de Barcelona","og_description":"La defensor\u00eda publica un informe que concluye que es necesario disponer de atenci\u00f3n espec\u00edfica para los casos de violencias no recientes.","og_url":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-al-ayuntamiento-a-reforzar-los-servicios-de-atencion-a-las-victimas-de-violencias-sexuales\/","og_site_name":"Sindicatura de Greuges de Barcelona","article_published_time":"2025-12-16T08:30:00+00:00","article_modified_time":"2025-12-18T10:23:37+00:00","og_image":[{"width":799,"height":534,"url":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/punt_lila_intinerant_resized_0.jpg","type":"image\/jpeg"}],"author":"Pablo","twitter_card":"summary_large_image","twitter_creator":"@sindicbarcelona","twitter_site":"@sindicbarcelona","twitter_misc":{"Escrito por":"Pablo","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-al-ayuntamiento-a-reforzar-los-servicios-de-atencion-a-las-victimas-de-violencias-sexuales\/#article","isPartOf":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-al-ayuntamiento-a-reforzar-los-servicios-de-atencion-a-las-victimas-de-violencias-sexuales\/"},"author":{"name":"Pablo","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#\/schema\/person\/0e5acffc350ffdbc97578159322c9452"},"headline":"La Sindicatura insta al Ayuntamiento a reforzar los servicios de atenci\u00f3n a las v\u00edctimas de violencias sexuales","datePublished":"2025-12-16T08:30:00+00:00","dateModified":"2025-12-18T10:23:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-al-ayuntamiento-a-reforzar-los-servicios-de-atencion-a-las-victimas-de-violencias-sexuales\/"},"wordCount":800,"publisher":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#organization"},"image":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-al-ayuntamiento-a-reforzar-los-servicios-de-atencion-a-las-victimas-de-violencias-sexuales\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/punt_lila_intinerant_resized_0.jpg","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-al-ayuntamiento-a-reforzar-los-servicios-de-atencion-a-las-victimas-de-violencias-sexuales\/","url":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-al-ayuntamiento-a-reforzar-los-servicios-de-atencion-a-las-victimas-de-violencias-sexuales\/","name":"La Sindicatura insta al Ayuntamiento a reforzar los servicios de atenci\u00f3n a las v\u00edctimas de violencias sexuales - Sindicatura de Greuges de Barcelona","isPartOf":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-al-ayuntamiento-a-reforzar-los-servicios-de-atencion-a-las-victimas-de-violencias-sexuales\/#primaryimage"},"image":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-al-ayuntamiento-a-reforzar-los-servicios-de-atencion-a-las-victimas-de-violencias-sexuales\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/punt_lila_intinerant_resized_0.jpg","datePublished":"2025-12-16T08:30:00+00:00","dateModified":"2025-12-18T10:23:37+00:00","description":"La defensor\u00eda publica un informe que concluye que es necesario disponer de atenci\u00f3n espec\u00edfica para los casos de violencias no recientes.","breadcrumb":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-al-ayuntamiento-a-reforzar-los-servicios-de-atencion-a-las-victimas-de-violencias-sexuales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-al-ayuntamiento-a-reforzar-los-servicios-de-atencion-a-las-victimas-de-violencias-sexuales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-al-ayuntamiento-a-reforzar-los-servicios-de-atencion-a-las-victimas-de-violencias-sexuales\/#primaryimage","url":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/punt_lila_intinerant_resized_0.jpg","contentUrl":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/punt_lila_intinerant_resized_0.jpg","width":799,"height":534},{"@type":"BreadcrumbList","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-al-ayuntamiento-a-reforzar-los-servicios-de-atencion-a-las-victimas-de-violencias-sexuales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.sindicaturabarcelona.cat\/es\/"},{"@type":"ListItem","position":2,"name":"La Sindicatura insta al Ayuntamiento a reforzar los servicios de atenci\u00f3n a las v\u00edctimas de violencias sexuales"}]},{"@type":"WebSite","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#website","url":"https:\/\/www.sindicaturabarcelona.cat\/es\/","name":"Sindicatura de Greuges de Barcelona","description":"La defensoria dels teus drets","publisher":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sindicaturabarcelona.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#organization","name":"Sindicatura de Greuges de Barcelona","url":"https:\/\/www.sindicaturabarcelona.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2023\/02\/logo_sindicatura.svg","contentUrl":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2023\/02\/logo_sindicatura.svg","caption":"Sindicatura de Greuges de Barcelona"},"image":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/sindicbarcelona","https:\/\/www.instagram.com\/sindicbarcelona\/","https:\/\/www.tiktok.com\/@sindicaturabcn","https:\/\/t.me\/sindicaturabarcelona"]},{"@type":"Person","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#\/schema\/person\/0e5acffc350ffdbc97578159322c9452","name":"Pablo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g","caption":"Pablo"},"url":"https:\/\/www.sindicaturabarcelona.cat\/es\/author\/pablo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/posts\/40889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/comments?post=40889"}],"version-history":[{"count":4,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/posts\/40889\/revisions"}],"predecessor-version":[{"id":40938,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/posts\/40889\/revisions\/40938"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/media\/40830"}],"wp:attachment":[{"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/media?parent=40889"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/tags?post=40889"},{"taxonomy":"drets","embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/drets?post=40889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}