{"id":36029,"date":"2025-03-14T08:00:00","date_gmt":"2025-03-14T06:00:00","guid":{"rendered":"https:\/\/www.sindicaturabarcelona.cat\/la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos\/"},"modified":"2025-03-14T10:11:28","modified_gmt":"2025-03-14T08:11:28","slug":"la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos","status":"publish","type":"post","link":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos\/","title":{"rendered":"La Sindicatura insta a TMB a evitar que las personas conductoras de bus se detengan en las paradas m\u00e1s de dos minutos con los motores encedidos\u00a0\u00a0"},"content":{"rendered":"\n<p>A ra\u00edz de una queja <strong>por las molestias que causan los paros prolongados, y con el motor en marcha, <\/strong><a href=\"https:\/\/www.tmb.cat\/es\/barcelona\/autobuses\/-\/lineabus\/H6#iss=https%3A%2F%2Fauth.tmb.cat%2Fauth%2Frealms%2Ftmb\"><strong>de los buses de la l\u00ednea H6<\/strong><\/a> en la parada de origen-final Metro Onze de Setembre, en la calle Pare Manyanet (<a href=\"https:\/\/ajuntament.barcelona.cat\/santandreu\/es\/el-distrito-y-sus-barrios\/sant-andreu-de-palomar\">Sant Andreu de Palomar<\/a>), la defensor\u00eda de la ciudad <a href=\"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/202502_Dret-descans-Medi-Ambient-Molesties-Sorolls-Bus-H6.pdf\">pide en su resoluci\u00f3n<\/a> que se garantice el derecho al descanso vecinal.<\/p>\n\n\n\n<p>Esta situaci\u00f3n, que se mantiene desde 2022, <strong>contraviene<\/strong> <strong>la <\/strong><a href=\"https:\/\/bcnroc.ajuntament.barcelona.cat\/jspui\/handle\/11703\/86859\"><strong>Ordenanza de medio ambiente municipal<\/strong><\/a>, que establece que \u00absalvo situaciones de congesti\u00f3n de tr\u00e1fico, est\u00e1 prohibido que los veh\u00edculos parados o en otros espacios p\u00fablicos permanezcan con los motores en marcha durante m\u00e1s de dos minutos\u00bb.<\/p>\n\n\n\n<p>El motivo principal de la queja es el ruido que se deriva, pero tambi\u00e9n existe una <strong>clara afectaci\u00f3n sobre la contaminaci\u00f3n atmosf\u00e9rica y, por tanto, sobre <\/strong><a href=\"https:\/\/www.sindicaturabarcelona.cat\/es\/drets\/derecho-al-medio-ambiente\/\"><strong>el derecho al medio ambiente<\/strong><\/a>. <strong>En el \u00e1rea metropolitana, los \u00edndices de poluci\u00f3n<\/strong>, que tienen una clara relaci\u00f3n con el tr\u00e1fico rodado, <strong>siguen por encima de lo que recomienda la Organizaci\u00f3n Mundial de la Salud (OMS)<\/strong>, si bien existe una <a href=\"https:\/\/www.barcelona.cat\/mobilitat\/es\/actualitat-i-recursos\/noticies\/baja-la-contaminacion-del-aire-a-barcelona-1470246\">tendencia descendente<\/a>.<\/p>\n\n\n\n<p>En el caso del bus H6, el <strong>ente que debe hacer cumplir la Ordenanza es <\/strong><a href=\"https:\/\/www.tmb.cat\/ca\/#iss=https%3A%2F%2Fauth.tmb.cat%2Fauth%2Frealms%2Ftmb\"><strong>Transports Metropolitans de Barcelona<\/strong><\/a> (TMB). La entidad asegura que ya ha detectado el problema y que <strong>ha llevado a cabo diversas medidas <\/strong>para abordarlo:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>reuniones peri\u00f3dicas en la cochera para recordar a las personas conductoras la obligaci\u00f3n de cumplir la Ordenanza y apagar los motores;<\/li>\n\n\n\n<li>poner en conocimiento al personal de conducci\u00f3n de las quejas sobre este hecho;<\/li>\n\n\n\n<li>explicaci\u00f3n en las reuniones de formaci\u00f3n y reuniones telem\u00e1ticas;<\/li>\n\n\n\n<li>advertencia verbal a la persona conductora que ha cometido la infracci\u00f3n.<\/li>\n<\/ul>\n\n\n\n<p>Por el momento, <strong>no consta que se haya tramitado ning\u00fan expediente sancionador ni disciplinario<\/strong> contra esta conducta, ya que, seg\u00fan TMB, no existe ninguna prueba que lo acredite. Dado lo anterior, el tiempo que dura la situaci\u00f3n y la reiteraci\u00f3n de la infracci\u00f3n, las acciones preventivas de la entidad para hacer cumplir esta normativa no han sido eficaces.<\/p>\n\n\n\n<p>De hecho, <strong>la Sindicatura ya ha recibido varias quejas<\/strong> <strong>por las molestias causadas por las personas conductoras de autob\u00fas por este mismo motivo<\/strong>. <a href=\"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/202411_dret-al-descans-i-dret-al-medi-ambient_sorolls-al-final-de-linia-autobus-59.pdf\">La \u00faltima se public\u00f3 en noviembre<\/a>, y afectaba a la l\u00ednea 59, en la parada de origen-final ubicada en la gran v\u00eda Carlos III, 101 (Distrito de Les Corts). Una de las conclusiones de aquella resoluci\u00f3n era <strong>la recomendaci\u00f3n a TMB de que renovara la flota de autobuses, y que apueste por veh\u00edculos menos contaminantes y m\u00e1s silenciosos<\/strong>, un punto sobre el que se vuelve a incidir en la resoluci\u00f3n relativa a la l\u00ednea H6.<\/p>\n\n\n\n<p><strong>Otras resoluciones recientes por contaminaci\u00f3n ac\u00fastica derivadas del transporte p\u00fablico<\/strong> fueron en febrero, por el ruido que generaba <a href=\"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/202502_Dret-descans-Transport-public-Ascensor-Metro-Maragall.pdf\">el ascensor de la parada de metro Maragall<\/a> y el <a href=\"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/202502_Dret-descans-Contaminacio-Acustica-Generador-metro-Clot.pdf\">generador en la parada de metro Clot<\/a>, y en octubre, por las <a href=\"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/202411_dret-al-descans-i-dret-al-medi-ambient_sorolls-al-final-de-linia-autobus-59.pdf\">molestias que causa una estaci\u00f3n de Bicing en el Distrito de Sarri\u00e0 &#8211; Sant Gervasi<\/a>.<\/p>\n\n\n\n<p>Por todo ello, la Sindicatura de Greuges de Barcelona concluye que la actuaci\u00f3n de <strong>TMB no ha sido ajustada a derecho<\/strong>, con una clara afectaci\u00f3n <a href=\"https:\/\/www.sindicaturabarcelona.cat\/ca\/drets\/dret-al-descans\/\">al derecho al descanso de la ciudadan\u00eda<\/a>, y recomienda a Transports Metropolitans que:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>elabore un plan de acci\u00f3n<\/strong> para evitar que los conductores y conductoras de la l\u00ednea H6 mantengan los motores en marcha m\u00e1s de dos minutos en la parada de origen-final Metro Onze de Setembre<\/li>\n\n\n\n<li>valore la posibilidad de realizar una <strong>acci\u00f3n coordinada con la <\/strong><a href=\"https:\/\/ajuntament.barcelona.cat\/guardiaurbana\/es\/\"><strong>Guardia Urbana<\/strong><\/a> para denunciar estas infracciones<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>A ra\u00edz de una queja por las molestias que causan los paros prolongados, y con el motor en marcha, de los buses de la l\u00ednea H6 en la parada de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":36022,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"tags":[],"drets":[1477,1592,1596],"class_list":["post-36029","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","drets-ciudad-habitable-y-sostenible","drets-derecho-al-medio-ambiente","drets-derecho-al-descanso"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Sindicatura insta a TMB a evitar que las personas conductoras de bus se detengan en las paradas m\u00e1s de dos minutos con los motores encedidos\u00a0\u00a0 - Sindicatura de Greuges de Barcelona<\/title>\n<meta name=\"description\" content=\"A ra\u00edz de una queja por las molestias que causan los paros prolongados y con el motor en marcha de los buses de la l\u00ednea H6 en Sant Andreu.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Sindicatura insta a TMB a evitar que las personas conductoras de bus se detengan en las paradas m\u00e1s de dos minutos con los motores encedidos\u00a0\u00a0 - Sindicatura de Greuges de Barcelona\" \/>\n<meta property=\"og:description\" content=\"A ra\u00edz de una queja por las molestias que causan los paros prolongados y con el motor en marcha de los buses de la l\u00ednea H6 en Sant Andreu.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos\/\" \/>\n<meta property=\"og:site_name\" content=\"Sindicatura de Greuges de Barcelona\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-14T06:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-14T08:11:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/Bus2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1363\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pablo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sindicbarcelona\" \/>\n<meta name=\"twitter:site\" content=\"@sindicbarcelona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pablo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos\\\/\"},\"author\":{\"name\":\"Pablo\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#\\\/schema\\\/person\\\/0e5acffc350ffdbc97578159322c9452\"},\"headline\":\"La Sindicatura insta a TMB a evitar que las personas conductoras de bus se detengan en las paradas m\u00e1s de dos minutos con los motores encedidos\u00a0\u00a0\",\"datePublished\":\"2025-03-14T06:00:00+00:00\",\"dateModified\":\"2025-03-14T08:11:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos\\\/\"},\"wordCount\":640,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/Bus2.jpg\",\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos\\\/\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos\\\/\",\"name\":\"La Sindicatura insta a TMB a evitar que las personas conductoras de bus se detengan en las paradas m\u00e1s de dos minutos con los motores encedidos\u00a0\u00a0 - Sindicatura de Greuges de Barcelona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/Bus2.jpg\",\"datePublished\":\"2025-03-14T06:00:00+00:00\",\"dateModified\":\"2025-03-14T08:11:28+00:00\",\"description\":\"A ra\u00edz de una queja por las molestias que causan los paros prolongados y con el motor en marcha de los buses de la l\u00ednea H6 en Sant Andreu.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/Bus2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/Bus2.jpg\",\"width\":2048,\"height\":1363,\"caption\":\"Bus Autob\u00fas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Sindicatura insta a TMB a evitar que las personas conductoras de bus se detengan en las paradas m\u00e1s de dos minutos con los motores encedidos\u00a0\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/\",\"name\":\"Sindicatura de Greuges de Barcelona\",\"description\":\"La defensoria dels teus drets\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#organization\",\"name\":\"Sindicatura de Greuges de Barcelona\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/logo_sindicatura.svg\",\"contentUrl\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/logo_sindicatura.svg\",\"caption\":\"Sindicatura de Greuges de Barcelona\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/sindicbarcelona\",\"https:\\\/\\\/www.instagram.com\\\/sindicbarcelona\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@sindicaturabcn\",\"https:\\\/\\\/t.me\\\/sindicaturabarcelona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#\\\/schema\\\/person\\\/0e5acffc350ffdbc97578159322c9452\",\"name\":\"Pablo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g\",\"caption\":\"Pablo\"},\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/author\\\/pablo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Sindicatura insta a TMB a evitar que las personas conductoras de bus se detengan en las paradas m\u00e1s de dos minutos con los motores encedidos\u00a0\u00a0 - Sindicatura de Greuges de Barcelona","description":"A ra\u00edz de una queja por las molestias que causan los paros prolongados y con el motor en marcha de los buses de la l\u00ednea H6 en Sant Andreu.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos\/","og_locale":"es_ES","og_type":"article","og_title":"La Sindicatura insta a TMB a evitar que las personas conductoras de bus se detengan en las paradas m\u00e1s de dos minutos con los motores encedidos\u00a0\u00a0 - Sindicatura de Greuges de Barcelona","og_description":"A ra\u00edz de una queja por las molestias que causan los paros prolongados y con el motor en marcha de los buses de la l\u00ednea H6 en Sant Andreu.","og_url":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos\/","og_site_name":"Sindicatura de Greuges de Barcelona","article_published_time":"2025-03-14T06:00:00+00:00","article_modified_time":"2025-03-14T08:11:28+00:00","og_image":[{"width":2048,"height":1363,"url":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/Bus2.jpg","type":"image\/jpeg"}],"author":"Pablo","twitter_card":"summary_large_image","twitter_creator":"@sindicbarcelona","twitter_site":"@sindicbarcelona","twitter_misc":{"Escrito por":"Pablo","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos\/#article","isPartOf":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos\/"},"author":{"name":"Pablo","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#\/schema\/person\/0e5acffc350ffdbc97578159322c9452"},"headline":"La Sindicatura insta a TMB a evitar que las personas conductoras de bus se detengan en las paradas m\u00e1s de dos minutos con los motores encedidos\u00a0\u00a0","datePublished":"2025-03-14T06:00:00+00:00","dateModified":"2025-03-14T08:11:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos\/"},"wordCount":640,"publisher":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#organization"},"image":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/Bus2.jpg","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos\/","url":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos\/","name":"La Sindicatura insta a TMB a evitar que las personas conductoras de bus se detengan en las paradas m\u00e1s de dos minutos con los motores encedidos\u00a0\u00a0 - Sindicatura de Greuges de Barcelona","isPartOf":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos\/#primaryimage"},"image":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/Bus2.jpg","datePublished":"2025-03-14T06:00:00+00:00","dateModified":"2025-03-14T08:11:28+00:00","description":"A ra\u00edz de una queja por las molestias que causan los paros prolongados y con el motor en marcha de los buses de la l\u00ednea H6 en Sant Andreu.","breadcrumb":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos\/#primaryimage","url":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/Bus2.jpg","contentUrl":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/Bus2.jpg","width":2048,"height":1363,"caption":"Bus Autob\u00fas"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-insta-tmb-a-evitar-que-les-persones-conductores-de-bus-sestiguin-aturats-a-les-parades-mes-de-dos-minuts-amb-els-motors-encesos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.sindicaturabarcelona.cat\/es\/"},{"@type":"ListItem","position":2,"name":"La Sindicatura insta a TMB a evitar que las personas conductoras de bus se detengan en las paradas m\u00e1s de dos minutos con los motores encedidos\u00a0\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#website","url":"https:\/\/www.sindicaturabarcelona.cat\/es\/","name":"Sindicatura de Greuges de Barcelona","description":"La defensoria dels teus drets","publisher":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sindicaturabarcelona.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#organization","name":"Sindicatura de Greuges de Barcelona","url":"https:\/\/www.sindicaturabarcelona.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2023\/02\/logo_sindicatura.svg","contentUrl":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2023\/02\/logo_sindicatura.svg","caption":"Sindicatura de Greuges de Barcelona"},"image":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/sindicbarcelona","https:\/\/www.instagram.com\/sindicbarcelona\/","https:\/\/www.tiktok.com\/@sindicaturabcn","https:\/\/t.me\/sindicaturabarcelona"]},{"@type":"Person","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#\/schema\/person\/0e5acffc350ffdbc97578159322c9452","name":"Pablo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g","caption":"Pablo"},"url":"https:\/\/www.sindicaturabarcelona.cat\/es\/author\/pablo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/posts\/36029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/comments?post=36029"}],"version-history":[{"count":1,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/posts\/36029\/revisions"}],"predecessor-version":[{"id":36031,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/posts\/36029\/revisions\/36031"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/media\/36022"}],"wp:attachment":[{"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/media?parent=36029"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/tags?post=36029"},{"taxonomy":"drets","embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/drets?post=36029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}