{"id":34944,"date":"2025-01-30T08:00:00","date_gmt":"2025-01-30T06:00:00","guid":{"rendered":"https:\/\/www.sindicaturabarcelona.cat\/?p=34944"},"modified":"2025-02-10T10:19:09","modified_gmt":"2025-02-10T08:19:09","slug":"la-sindicatura-de-greuges-de-barcelona-sofereix-com-a-mediadora-en-el-cas-de-la-casa-orsola","status":"publish","type":"post","link":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-de-greuges-de-barcelona-sofereix-com-a-mediadora-en-el-cas-de-la-casa-orsola\/","title":{"rendered":"La Sindicatura de Greuges de Barcelona se ofrece como mediadora en el caso de la Casa Orsola"},"content":{"rendered":"\n<p>Debido a la proximidad del primer desahucio, acordado judicialmente, del vecindario de la Casa Orsola (calle Cal\u00e0bria, 137 y calle Consell de Cent, 122 de Barcelona), previsto para el 31 de enero de este a\u00f1o, <strong>desde la Sindicatura de Greuges de Barcelona consideramos que es necesario realizar todos los esfuerzos posibles para encontrar un espacio de di\u00e1logo y reflexi\u00f3n capaz de llegar a una soluci\u00f3n de consenso entre el vecindario de la finca y los propietarios del inmueble<\/strong> (Lioness Inversiones, SLU).<\/p>\n\n\n\n<p>Ante el posible desahucio y la convocatoria de movilizaciones que pueden llegar a alterar el orden p\u00fablico en nuestra ciudad, <strong>el S\u00edndic de Greuges de Barcelona, David Bondia Garcia, ofrece su predisposici\u00f3n a intervenir como mediador para buscar un acuerdo viable y realista entre las partes, al tiempo que insta al Ayuntamiento de Barcelona a proponer soluciones que, dentro de su marco competencial, preserven el derecho a la vivienda.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Debido a la proximidad del primer desahucio, acordado judicialmente, del vecindario de la Casa Orsola (calle Cal\u00e0bria, 137 y calle Consell de Cent, 122 de Barcelona), previsto para el 31 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":35255,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"tags":[],"drets":[1475,1577],"class_list":["post-34944","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","drets-ciudad-equitativa","drets-derecho-a-la-vivienda"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Sindicatura de Greuges de Barcelona se ofrece como mediadora en el caso de la Casa Orsola - Sindicatura de Greuges de Barcelona<\/title>\n<meta name=\"description\" content=\"Hay que hacer todos los esfuerzos para encontrar un espacio de di\u00e1logo y llegar a un consenso entre los vecinos y los propietarios.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-de-greuges-de-barcelona-sofereix-com-a-mediadora-en-el-cas-de-la-casa-orsola\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Sindicatura de Greuges de Barcelona se ofrece como mediadora en el caso de la Casa Orsola - Sindicatura de Greuges de Barcelona\" \/>\n<meta property=\"og:description\" content=\"Hay que hacer todos los esfuerzos para encontrar un espacio de di\u00e1logo y llegar a un consenso entre los vecinos y los propietarios.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-de-greuges-de-barcelona-sofereix-com-a-mediadora-en-el-cas-de-la-casa-orsola\/\" \/>\n<meta property=\"og:site_name\" content=\"Sindicatura de Greuges de Barcelona\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-30T06:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-10T08:19:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/IMG_8651-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1710\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pablo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sindicbarcelona\" \/>\n<meta name=\"twitter:site\" content=\"@sindicbarcelona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pablo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-de-greuges-de-barcelona-sofereix-com-a-mediadora-en-el-cas-de-la-casa-orsola\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-de-greuges-de-barcelona-sofereix-com-a-mediadora-en-el-cas-de-la-casa-orsola\\\/\"},\"author\":{\"name\":\"Pablo\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#\\\/schema\\\/person\\\/0e5acffc350ffdbc97578159322c9452\"},\"headline\":\"La Sindicatura de Greuges de Barcelona se ofrece como mediadora en el caso de la Casa Orsola\",\"datePublished\":\"2025-01-30T06:00:00+00:00\",\"dateModified\":\"2025-02-10T08:19:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-de-greuges-de-barcelona-sofereix-com-a-mediadora-en-el-cas-de-la-casa-orsola\\\/\"},\"wordCount\":172,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-de-greuges-de-barcelona-sofereix-com-a-mediadora-en-el-cas-de-la-casa-orsola\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/IMG_8651-scaled.jpg\",\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-de-greuges-de-barcelona-sofereix-com-a-mediadora-en-el-cas-de-la-casa-orsola\\\/\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-de-greuges-de-barcelona-sofereix-com-a-mediadora-en-el-cas-de-la-casa-orsola\\\/\",\"name\":\"La Sindicatura de Greuges de Barcelona se ofrece como mediadora en el caso de la Casa Orsola - Sindicatura de Greuges de Barcelona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-de-greuges-de-barcelona-sofereix-com-a-mediadora-en-el-cas-de-la-casa-orsola\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-de-greuges-de-barcelona-sofereix-com-a-mediadora-en-el-cas-de-la-casa-orsola\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/IMG_8651-scaled.jpg\",\"datePublished\":\"2025-01-30T06:00:00+00:00\",\"dateModified\":\"2025-02-10T08:19:09+00:00\",\"description\":\"Hay que hacer todos los esfuerzos para encontrar un espacio de di\u00e1logo y llegar a un consenso entre los vecinos y los propietarios.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-de-greuges-de-barcelona-sofereix-com-a-mediadora-en-el-cas-de-la-casa-orsola\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-de-greuges-de-barcelona-sofereix-com-a-mediadora-en-el-cas-de-la-casa-orsola\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-de-greuges-de-barcelona-sofereix-com-a-mediadora-en-el-cas-de-la-casa-orsola\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/IMG_8651-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/IMG_8651-scaled.jpg\",\"width\":2560,\"height\":1710},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindicatura-de-greuges-de-barcelona-sofereix-com-a-mediadora-en-el-cas-de-la-casa-orsola\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Sindicatura de Greuges de Barcelona se ofrece como mediadora en el caso de la Casa Orsola\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/\",\"name\":\"Sindicatura de Greuges de Barcelona\",\"description\":\"La defensoria dels teus drets\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#organization\",\"name\":\"Sindicatura de Greuges de Barcelona\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/logo_sindicatura.svg\",\"contentUrl\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/logo_sindicatura.svg\",\"caption\":\"Sindicatura de Greuges de Barcelona\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/sindicbarcelona\",\"https:\\\/\\\/www.instagram.com\\\/sindicbarcelona\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@sindicaturabcn\",\"https:\\\/\\\/t.me\\\/sindicaturabarcelona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#\\\/schema\\\/person\\\/0e5acffc350ffdbc97578159322c9452\",\"name\":\"Pablo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g\",\"caption\":\"Pablo\"},\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/author\\\/pablo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Sindicatura de Greuges de Barcelona se ofrece como mediadora en el caso de la Casa Orsola - Sindicatura de Greuges de Barcelona","description":"Hay que hacer todos los esfuerzos para encontrar un espacio de di\u00e1logo y llegar a un consenso entre los vecinos y los propietarios.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-de-greuges-de-barcelona-sofereix-com-a-mediadora-en-el-cas-de-la-casa-orsola\/","og_locale":"es_ES","og_type":"article","og_title":"La Sindicatura de Greuges de Barcelona se ofrece como mediadora en el caso de la Casa Orsola - Sindicatura de Greuges de Barcelona","og_description":"Hay que hacer todos los esfuerzos para encontrar un espacio de di\u00e1logo y llegar a un consenso entre los vecinos y los propietarios.","og_url":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-de-greuges-de-barcelona-sofereix-com-a-mediadora-en-el-cas-de-la-casa-orsola\/","og_site_name":"Sindicatura de Greuges de Barcelona","article_published_time":"2025-01-30T06:00:00+00:00","article_modified_time":"2025-02-10T08:19:09+00:00","og_image":[{"width":2560,"height":1710,"url":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/IMG_8651-scaled.jpg","type":"image\/jpeg"}],"author":"Pablo","twitter_card":"summary_large_image","twitter_creator":"@sindicbarcelona","twitter_site":"@sindicbarcelona","twitter_misc":{"Escrito por":"Pablo","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-de-greuges-de-barcelona-sofereix-com-a-mediadora-en-el-cas-de-la-casa-orsola\/#article","isPartOf":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-de-greuges-de-barcelona-sofereix-com-a-mediadora-en-el-cas-de-la-casa-orsola\/"},"author":{"name":"Pablo","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#\/schema\/person\/0e5acffc350ffdbc97578159322c9452"},"headline":"La Sindicatura de Greuges de Barcelona se ofrece como mediadora en el caso de la Casa Orsola","datePublished":"2025-01-30T06:00:00+00:00","dateModified":"2025-02-10T08:19:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-de-greuges-de-barcelona-sofereix-com-a-mediadora-en-el-cas-de-la-casa-orsola\/"},"wordCount":172,"publisher":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#organization"},"image":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-de-greuges-de-barcelona-sofereix-com-a-mediadora-en-el-cas-de-la-casa-orsola\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/IMG_8651-scaled.jpg","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-de-greuges-de-barcelona-sofereix-com-a-mediadora-en-el-cas-de-la-casa-orsola\/","url":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-de-greuges-de-barcelona-sofereix-com-a-mediadora-en-el-cas-de-la-casa-orsola\/","name":"La Sindicatura de Greuges de Barcelona se ofrece como mediadora en el caso de la Casa Orsola - Sindicatura de Greuges de Barcelona","isPartOf":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-de-greuges-de-barcelona-sofereix-com-a-mediadora-en-el-cas-de-la-casa-orsola\/#primaryimage"},"image":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-de-greuges-de-barcelona-sofereix-com-a-mediadora-en-el-cas-de-la-casa-orsola\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/IMG_8651-scaled.jpg","datePublished":"2025-01-30T06:00:00+00:00","dateModified":"2025-02-10T08:19:09+00:00","description":"Hay que hacer todos los esfuerzos para encontrar un espacio de di\u00e1logo y llegar a un consenso entre los vecinos y los propietarios.","breadcrumb":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-de-greuges-de-barcelona-sofereix-com-a-mediadora-en-el-cas-de-la-casa-orsola\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-de-greuges-de-barcelona-sofereix-com-a-mediadora-en-el-cas-de-la-casa-orsola\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-de-greuges-de-barcelona-sofereix-com-a-mediadora-en-el-cas-de-la-casa-orsola\/#primaryimage","url":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/IMG_8651-scaled.jpg","contentUrl":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/IMG_8651-scaled.jpg","width":2560,"height":1710},{"@type":"BreadcrumbList","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindicatura-de-greuges-de-barcelona-sofereix-com-a-mediadora-en-el-cas-de-la-casa-orsola\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.sindicaturabarcelona.cat\/es\/"},{"@type":"ListItem","position":2,"name":"La Sindicatura de Greuges de Barcelona se ofrece como mediadora en el caso de la Casa Orsola"}]},{"@type":"WebSite","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#website","url":"https:\/\/www.sindicaturabarcelona.cat\/es\/","name":"Sindicatura de Greuges de Barcelona","description":"La defensoria dels teus drets","publisher":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sindicaturabarcelona.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#organization","name":"Sindicatura de Greuges de Barcelona","url":"https:\/\/www.sindicaturabarcelona.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2023\/02\/logo_sindicatura.svg","contentUrl":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2023\/02\/logo_sindicatura.svg","caption":"Sindicatura de Greuges de Barcelona"},"image":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/sindicbarcelona","https:\/\/www.instagram.com\/sindicbarcelona\/","https:\/\/www.tiktok.com\/@sindicaturabcn","https:\/\/t.me\/sindicaturabarcelona"]},{"@type":"Person","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#\/schema\/person\/0e5acffc350ffdbc97578159322c9452","name":"Pablo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g","caption":"Pablo"},"url":"https:\/\/www.sindicaturabarcelona.cat\/es\/author\/pablo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/posts\/34944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/comments?post=34944"}],"version-history":[{"count":1,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/posts\/34944\/revisions"}],"predecessor-version":[{"id":34946,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/posts\/34944\/revisions\/34946"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/media\/35255"}],"wp:attachment":[{"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/media?parent=34944"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/tags?post=34944"},{"taxonomy":"drets","embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/drets?post=34944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}