{"id":13931,"date":"2022-05-10T09:58:19","date_gmt":"2022-05-10T07:58:19","guid":{"rendered":"https:\/\/www.sindicaturabarcelona.cat\/?p=13931"},"modified":"2022-05-10T09:59:18","modified_gmt":"2022-05-10T07:59:18","slug":"colegi-teatre-barcelona-sindicatura-advierte-consorcio-educacion-protocolos-violencias-machistas","status":"publish","type":"post","link":"https:\/\/www.sindicaturabarcelona.cat\/es\/colegi-teatre-barcelona-sindicatura-advierte-consorcio-educacion-protocolos-violencias-machistas\/","title":{"rendered":"Col\u00b7legi del Teatre de Barcelona: La Sindicatura advierte al Consorcio de Educaci\u00f3n de la obligaci\u00f3n de garantizar que todas las escuelas dispongan de protocolos para erradicar las violencias machistas"},"content":{"rendered":"\n<p class=\"has-text-align-justify\">A ra\u00edz de la actuaci\u00f3n de oficio abierta por el caso del Col\u00b7legi del Teatre, la Sindicatura de Greuges de Barcelona ha advertido al <strong>Consorcio de Educaci\u00f3n de Barcelona<\/strong> de su obligaci\u00f3n de garantizar que todas las escuelas dispongan de las herramientas, documentaci\u00f3n y protocolos adecuados para favorecer una buena convivencia y clima escolar, y que se aseguren de su conocimiento e implementaci\u00f3n.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Por otro lado, la Sindicatura <strong>tambi\u00e9n ha recomendado al Consorcio de Educaci\u00f3n de Barcelona<\/strong> que, en cumplimiento de las tareas que tiene encomendadas, intensifique e impulse las actuaciones de difusi\u00f3n y formaci\u00f3n de toda la comunidad educativa encaminadas a erradicar las violencias en todas las escuelas, sean p\u00fablicas, concertadas o privadas.<\/p>\n\n\n\n<p><strong><span style=\"text-decoration: underline;\" class=\"ek-underline\">El inicio de la actuaci\u00f3n de oficio<\/span><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify\">A trav\u00e9s de los medios de comunicaci\u00f3n, la Sindicatura de Greuges de la ciudad conoci\u00f3 la noticia de la instancia que trece exalumnos presentaron en el Col\u00b7legi del Teatre de Barcelona, en fecha 28 de diciembre de 2021. En ella se exponen situaciones de acosos, abusos, vejaciones, y vulneraciones de derechos por parte de varios profesores entre los a\u00f1os 2005 y 2020. <strong>Estas personas tambi\u00e9n explicaban que, en su momento, pusieron en conocimiento de la direcci\u00f3n de la escuela los hechos y que esta no hizo ninguna actuaci\u00f3n al respecto.<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify\">La Sindicatura se interes\u00f3 por los hechos denunciados por el&nbsp;antiguo alumnado del Col\u00b7legi del Teatre para evaluar si se hab\u00edan vulnerado los derechos humanos y libertades fundamentales de las mujeres recogidos, entre otros, en la <em>Declaraci\u00f3n sobre la eliminaci\u00f3n de la violencia contra la mujer (1993)<\/em> y en la <em>Ley 5\/2008, de 24 de abril, del derecho de las mujeres a erradicar la violencia machista<\/em>. En el marco de esta <a href=\"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2022\/05\/05_Colegi-del-Teatre.pdf\" target=\"_blank\" aria-label=\"actuaci\u00f3n de oficio (opens in a new tab)\" rel=\"noreferrer noopener\" class=\"ek-link\">actuaci\u00f3n de oficio<\/a>, en fecha 19 de enero de 2022, <strong>se solicit\u00f3 informaci\u00f3n al Consorcio de Educaci\u00f3n de Barcelona (CEB)&nbsp;y al Col\u00b7legi del Teatre de Barcelona<\/strong> para saber qu\u00e9 conocimiento ten\u00edan de los hechos y cu\u00e1les hab\u00edan sido las actuaciones impulsadas para proteger y garantizar el buen trato de las j\u00f3venes.<\/p>\n\n\n\n<p><strong><span style=\"text-decoration: underline;\" class=\"ek-underline\">La normativa vinculada a la violencia machista<\/span><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify\">Los hechos que estas exalumnas han rebelado en la carta de denuncia constatan <strong>la violencia machista que sufrieron en la escuela y su entorno<\/strong>. Naciones Unidas afirma en el pre\u00e1mbulo de la Declaraci\u00f3n sobre la eliminaci\u00f3n de la violencia contra la mujer (1993) que esta constituye <strong>una violaci\u00f3n de los derechos humanos y las libertades fundamentales.<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify\">La <em>Ley catalana 5\/2008 del derecho de las mujeres a erradicar la violencia machista<\/em> tambi\u00e9n la define <strong>como una violaci\u00f3n de los derechos humanos<\/strong>. Adem\u00e1s, es una manifestaci\u00f3n de la discriminaci\u00f3n y desigualdad existentes en el marco de un <strong>sistema de relaciones de poder desiguales entre hombres y mujeres<\/strong>. Esta violencia se produce por medios f\u00edsicos, econ\u00f3micos o psicol\u00f3gicos, incluidas las amenazas, las intimidaciones y las coacciones, y tiene como resultado un da\u00f1o o un sufrimiento f\u00edsico, sexual o psicol\u00f3gico.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Esta Ley reconoce el <strong>entorno educativo<\/strong> como un \u00e1mbito espec\u00edfico <strong>donde se puede manifestar la violencia machista entre los miembros de su comunidad<\/strong> en actuaciones como el acoso, el abuso sexual, el maltrato f\u00edsico, sexual, ps\u00edquico o emocional. Las denuncias efectuadas por las exalumnas del Col\u00b7legi del Teatre est\u00e1n relacionadas con las violencias que pueden producirse en el entorno educativo, supuesto contemplado en esta norma.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Por \u00faltimo, la <em>Ley 12\/2009 de educaci\u00f3n<\/em> contempla las <strong>escuelas como espacio seguros<\/strong> donde se deben respetar los principios democr\u00e1ticos de convivencia, y los derechos y las libertades fundamentales. El derecho en una educaci\u00f3n integral incluye, entre otras manifestaciones, el <strong>derecho a la protecci\u00f3n contra toda agresi\u00f3n f\u00edsica, emocional o moral, as\u00ed como el respeto del alumnado a su integridad f\u00edsica, su intimidad y su dignidad personal.<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify\"><span style=\"text-decoration: underline;\" class=\"ek-underline\"><strong>Las actuaciones posteriores a las denuncias<\/strong><\/span><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>El profesor vinculado a las denuncias ha presentado su dimisi\u00f3n. La escuela la ha aceptado y ya no forma parte del claustro del centro.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>Se ha actualizado el Proyecto de Convivencia y el organigrama del centro con un esp\u00edritu de autocr\u00edtica y de b\u00fasqueda de v\u00edas para mejorar la calidad educativa.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>Se han organizado reuniones con el alumnado para tratar el tema y hacer aflorar el posible malestar o situaciones que fueran reprobables, as\u00ed como incitar el alumnado para que aporte sugerencias. Se han facilitado espacios y momentos para que el alumnado se pueda reunir, y se ha iniciado un plan de formaci\u00f3n del profesorado relacionado con el acoso y el abuso de poder.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>Se ha intensificado el Plan de Acci\u00f3n Tutorial, insistiendo especialmente en los valores que impregnan el centro (respeto, democracia, participaci\u00f3n, sensibilidad&#8230;).<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>Ha aumentado el inter\u00e9s por parte del alumnado y del profesorado para crear un buen clima de convivencia y ser conscientes de su importancia.<\/li><\/ul>\n\n\n\n<p><strong><span style=\"text-decoration: underline;\" class=\"ek-underline\">Las consideraciones de la Sindicatura<\/span><\/strong><\/p>\n\n\n\n<p class=\"has-text-align-justify\">En el caso del Col\u00b7legi del Teatre de Barcelona, <strong>la violencia<\/strong>, expl\u00edcita e impl\u00edcita, <strong>era ejercida por el profesorado<\/strong>, comportamiento que todav\u00eda a\u00f1ade m\u00e1s gravedad a los hechos. Adem\u00e1s, las exalumnas han expuesto la <strong>complicidad y pasividad del resto del claustro y la direcci\u00f3n, los principales encargados de impulsar y garantizar el buen clima escolar. Han explicado que eran situaciones conocidas por todo el mundo y que las v\u00edctimas no recibieron la ayuda esperada por el centro<\/strong>.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">El centro es el responsable m\u00e1s directo y pr\u00f3ximo en la implantaci\u00f3n y activaci\u00f3n de los protocolos de prevenci\u00f3n y protecci\u00f3n de la violencia, que tienen que ser conocidos y difundidos entre toda la comunidad educativa. <strong>La misma escuela ha reconocido su responsabilidad en los d\u00e9ficits existentes en la prevenci\u00f3n y atenci\u00f3n de la violencia.<\/strong> Y ha informado que ha iniciado actuaciones para cambiar las din\u00e1micas relacionales entre los miembros de la comunidad educativa.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">El primer paso que esta escuela ha dado correctamente es trabajar en la elaboraci\u00f3n de un <strong>nuevo Proyecto de Convivencia para generar un buen clima escolar<\/strong>. Tambi\u00e9n ha fomentado actuaciones de investigaci\u00f3n para conocer si hab\u00eda m\u00e1s alumnado afectado y para incentivar su participaci\u00f3n en el Proyecto de Convivencia.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Es necesario recordar que <strong>implementar un Proyecto de Convivencia en el marco del Proyecto Educativo es una obligaci\u00f3n legal que tienen todas las escuelas, ya sean p\u00fablicas, concertadas o privadas, del Servicio de Educaci\u00f3n de Catalu\u00f1a <\/strong>(<em>Resoluci\u00f3n del Departamento de Educaci\u00f3n ENS\/585\/2017, de 17 de marzo, modificada el 16 de julio 2020<\/em>). <strong>El Proyecto de Convivencia debe incluir los protocolos de prevenci\u00f3n, detecci\u00f3n e intervenci\u00f3n frente a situaciones de conflictos gravemente perjudiciales para la convivencia<\/strong>, como establece el punto 6 del anexo de la <em>Resoluci\u00f3n ENS\/585\/2017<\/em>.<\/p>\n\n\n\n<p class=\"has-text-align-justify\">Por otro lado, la <em>Ley 12\/2009<\/em> de educaci\u00f3n <strong>otorga a la inspecci\u00f3n de los servicios educativos las funciones de asegurar la aplicaci\u00f3n del ordenamiento y garantizar el ejercicio de derechos y el cumplimiento de los deberes que se derivan<\/strong>. La denuncia a esta escuela ha destapado sus deficiencias, pero tambi\u00e9n la <strong>insuficiente actuaci\u00f3n del <a href=\"https:\/\/www.edubcn.cat\/es\" target=\"_blank\" aria-label=\"Consorcio de Educaci\u00f3n de Barcelona (CEB) (opens in a new tab)\" rel=\"noreferrer noopener\" class=\"ek-link\">Consorcio de Educaci\u00f3n de Barcelona (CEB)<\/a>&nbsp;en el cumplimiento de la normativa por parte la escuela<\/strong>, que ni siquiera dispon\u00eda de la documentaci\u00f3n obligatoria (como un Proyecto de Convivencia adecuado). Una vez conocidos los hechos, el&nbsp;CEB&nbsp;ha iniciado un trabajo conjunto con la escuela para orientarla en el dise\u00f1o de esta herramienta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A ra\u00edz de la actuaci\u00f3n de oficio abierta por el caso del Col\u00b7legi del Teatre, la Sindicatura de Greuges de Barcelona ha advertido al Consorcio de Educaci\u00f3n de Barcelona de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":13929,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"tags":[],"drets":[1475],"class_list":["post-13931","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","drets-ciudad-equitativa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Col\u00b7legi del Teatre de Barcelona: La Sindicatura advierte al Consorcio de Educaci\u00f3n de la obligaci\u00f3n de garantizar que todas las escuelas dispongan de protocolos para erradicar las violencias machistas - Sindicatura de Greuges de Barcelona<\/title>\n<meta name=\"description\" content=\"La Sindicatura tambi\u00e9n recomienda que se intensifiquen las actuaciones de difusi\u00f3n y formaci\u00f3n encaminadas a erradicar las violencias en todas las escuelas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sindicaturabarcelona.cat\/es\/colegi-teatre-barcelona-sindicatura-advierte-consorcio-educacion-protocolos-violencias-machistas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Col\u00b7legi del Teatre de Barcelona: La Sindicatura advierte al Consorcio de Educaci\u00f3n de la obligaci\u00f3n de garantizar que todas las escuelas dispongan de protocolos para erradicar las violencias machistas - Sindicatura de Greuges de Barcelona\" \/>\n<meta property=\"og:description\" content=\"La Sindicatura tambi\u00e9n recomienda que se intensifiquen las actuaciones de difusi\u00f3n y formaci\u00f3n encaminadas a erradicar las violencias en todas las escuelas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sindicaturabarcelona.cat\/es\/colegi-teatre-barcelona-sindicatura-advierte-consorcio-educacion-protocolos-violencias-machistas\/\" \/>\n<meta property=\"og:site_name\" content=\"Sindicatura de Greuges de Barcelona\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-10T07:58:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-10T07:59:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2022\/05\/ColTeatre1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"954\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pablo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sindicbarcelona\" \/>\n<meta name=\"twitter:site\" content=\"@sindicbarcelona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pablo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/colegi-teatre-barcelona-sindicatura-advierte-consorcio-educacion-protocolos-violencias-machistas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/colegi-teatre-barcelona-sindicatura-advierte-consorcio-educacion-protocolos-violencias-machistas\\\/\"},\"author\":{\"name\":\"Pablo\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#\\\/schema\\\/person\\\/0e5acffc350ffdbc97578159322c9452\"},\"headline\":\"Col\u00b7legi del Teatre de Barcelona: La Sindicatura advierte al Consorcio de Educaci\u00f3n de la obligaci\u00f3n de garantizar que todas las escuelas dispongan de protocolos para erradicar las violencias machistas\",\"datePublished\":\"2022-05-10T07:58:19+00:00\",\"dateModified\":\"2022-05-10T07:59:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/colegi-teatre-barcelona-sindicatura-advierte-consorcio-educacion-protocolos-violencias-machistas\\\/\"},\"wordCount\":1304,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/colegi-teatre-barcelona-sindicatura-advierte-consorcio-educacion-protocolos-violencias-machistas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/ColTeatre1.jpeg\",\"articleSection\":[\"General\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/colegi-teatre-barcelona-sindicatura-advierte-consorcio-educacion-protocolos-violencias-machistas\\\/\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/colegi-teatre-barcelona-sindicatura-advierte-consorcio-educacion-protocolos-violencias-machistas\\\/\",\"name\":\"Col\u00b7legi del Teatre de Barcelona: La Sindicatura advierte al Consorcio de Educaci\u00f3n de la obligaci\u00f3n de garantizar que todas las escuelas dispongan de protocolos para erradicar las violencias machistas - Sindicatura de Greuges de Barcelona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/colegi-teatre-barcelona-sindicatura-advierte-consorcio-educacion-protocolos-violencias-machistas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/colegi-teatre-barcelona-sindicatura-advierte-consorcio-educacion-protocolos-violencias-machistas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/ColTeatre1.jpeg\",\"datePublished\":\"2022-05-10T07:58:19+00:00\",\"dateModified\":\"2022-05-10T07:59:18+00:00\",\"description\":\"La Sindicatura tambi\u00e9n recomienda que se intensifiquen las actuaciones de difusi\u00f3n y formaci\u00f3n encaminadas a erradicar las violencias en todas las escuelas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/colegi-teatre-barcelona-sindicatura-advierte-consorcio-educacion-protocolos-violencias-machistas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/colegi-teatre-barcelona-sindicatura-advierte-consorcio-educacion-protocolos-violencias-machistas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/colegi-teatre-barcelona-sindicatura-advierte-consorcio-educacion-protocolos-violencias-machistas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/ColTeatre1.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/ColTeatre1.jpeg\",\"width\":954,\"height\":1024,\"caption\":\"Col\u00b7legi del Teatre\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/colegi-teatre-barcelona-sindicatura-advierte-consorcio-educacion-protocolos-violencias-machistas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Col\u00b7legi del Teatre de Barcelona: La Sindicatura advierte al Consorcio de Educaci\u00f3n de la obligaci\u00f3n de garantizar que todas las escuelas dispongan de protocolos para erradicar las violencias machistas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/\",\"name\":\"Sindicatura de Greuges de Barcelona\",\"description\":\"La defensoria dels teus drets\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#organization\",\"name\":\"Sindicatura de Greuges de Barcelona\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/logo_sindicatura.svg\",\"contentUrl\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/logo_sindicatura.svg\",\"caption\":\"Sindicatura de Greuges de Barcelona\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/sindicbarcelona\",\"https:\\\/\\\/www.instagram.com\\\/sindicbarcelona\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@sindicaturabcn\",\"https:\\\/\\\/t.me\\\/sindicaturabarcelona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#\\\/schema\\\/person\\\/0e5acffc350ffdbc97578159322c9452\",\"name\":\"Pablo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g\",\"caption\":\"Pablo\"},\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/author\\\/pablo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Col\u00b7legi del Teatre de Barcelona: La Sindicatura advierte al Consorcio de Educaci\u00f3n de la obligaci\u00f3n de garantizar que todas las escuelas dispongan de protocolos para erradicar las violencias machistas - Sindicatura de Greuges de Barcelona","description":"La Sindicatura tambi\u00e9n recomienda que se intensifiquen las actuaciones de difusi\u00f3n y formaci\u00f3n encaminadas a erradicar las violencias en todas las escuelas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sindicaturabarcelona.cat\/es\/colegi-teatre-barcelona-sindicatura-advierte-consorcio-educacion-protocolos-violencias-machistas\/","og_locale":"es_ES","og_type":"article","og_title":"Col\u00b7legi del Teatre de Barcelona: La Sindicatura advierte al Consorcio de Educaci\u00f3n de la obligaci\u00f3n de garantizar que todas las escuelas dispongan de protocolos para erradicar las violencias machistas - Sindicatura de Greuges de Barcelona","og_description":"La Sindicatura tambi\u00e9n recomienda que se intensifiquen las actuaciones de difusi\u00f3n y formaci\u00f3n encaminadas a erradicar las violencias en todas las escuelas.","og_url":"https:\/\/www.sindicaturabarcelona.cat\/es\/colegi-teatre-barcelona-sindicatura-advierte-consorcio-educacion-protocolos-violencias-machistas\/","og_site_name":"Sindicatura de Greuges de Barcelona","article_published_time":"2022-05-10T07:58:19+00:00","article_modified_time":"2022-05-10T07:59:18+00:00","og_image":[{"width":954,"height":1024,"url":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2022\/05\/ColTeatre1.jpeg","type":"image\/jpeg"}],"author":"Pablo","twitter_card":"summary_large_image","twitter_creator":"@sindicbarcelona","twitter_site":"@sindicbarcelona","twitter_misc":{"Escrito por":"Pablo","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/colegi-teatre-barcelona-sindicatura-advierte-consorcio-educacion-protocolos-violencias-machistas\/#article","isPartOf":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/colegi-teatre-barcelona-sindicatura-advierte-consorcio-educacion-protocolos-violencias-machistas\/"},"author":{"name":"Pablo","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#\/schema\/person\/0e5acffc350ffdbc97578159322c9452"},"headline":"Col\u00b7legi del Teatre de Barcelona: La Sindicatura advierte al Consorcio de Educaci\u00f3n de la obligaci\u00f3n de garantizar que todas las escuelas dispongan de protocolos para erradicar las violencias machistas","datePublished":"2022-05-10T07:58:19+00:00","dateModified":"2022-05-10T07:59:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/colegi-teatre-barcelona-sindicatura-advierte-consorcio-educacion-protocolos-violencias-machistas\/"},"wordCount":1304,"publisher":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#organization"},"image":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/colegi-teatre-barcelona-sindicatura-advierte-consorcio-educacion-protocolos-violencias-machistas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2022\/05\/ColTeatre1.jpeg","articleSection":["General"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/colegi-teatre-barcelona-sindicatura-advierte-consorcio-educacion-protocolos-violencias-machistas\/","url":"https:\/\/www.sindicaturabarcelona.cat\/es\/colegi-teatre-barcelona-sindicatura-advierte-consorcio-educacion-protocolos-violencias-machistas\/","name":"Col\u00b7legi del Teatre de Barcelona: La Sindicatura advierte al Consorcio de Educaci\u00f3n de la obligaci\u00f3n de garantizar que todas las escuelas dispongan de protocolos para erradicar las violencias machistas - Sindicatura de Greuges de Barcelona","isPartOf":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/colegi-teatre-barcelona-sindicatura-advierte-consorcio-educacion-protocolos-violencias-machistas\/#primaryimage"},"image":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/colegi-teatre-barcelona-sindicatura-advierte-consorcio-educacion-protocolos-violencias-machistas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2022\/05\/ColTeatre1.jpeg","datePublished":"2022-05-10T07:58:19+00:00","dateModified":"2022-05-10T07:59:18+00:00","description":"La Sindicatura tambi\u00e9n recomienda que se intensifiquen las actuaciones de difusi\u00f3n y formaci\u00f3n encaminadas a erradicar las violencias en todas las escuelas.","breadcrumb":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/colegi-teatre-barcelona-sindicatura-advierte-consorcio-educacion-protocolos-violencias-machistas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sindicaturabarcelona.cat\/es\/colegi-teatre-barcelona-sindicatura-advierte-consorcio-educacion-protocolos-violencias-machistas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/colegi-teatre-barcelona-sindicatura-advierte-consorcio-educacion-protocolos-violencias-machistas\/#primaryimage","url":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2022\/05\/ColTeatre1.jpeg","contentUrl":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2022\/05\/ColTeatre1.jpeg","width":954,"height":1024,"caption":"Col\u00b7legi del Teatre"},{"@type":"BreadcrumbList","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/colegi-teatre-barcelona-sindicatura-advierte-consorcio-educacion-protocolos-violencias-machistas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.sindicaturabarcelona.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Col\u00b7legi del Teatre de Barcelona: La Sindicatura advierte al Consorcio de Educaci\u00f3n de la obligaci\u00f3n de garantizar que todas las escuelas dispongan de protocolos para erradicar las violencias machistas"}]},{"@type":"WebSite","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#website","url":"https:\/\/www.sindicaturabarcelona.cat\/es\/","name":"Sindicatura de Greuges de Barcelona","description":"La defensoria dels teus drets","publisher":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sindicaturabarcelona.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#organization","name":"Sindicatura de Greuges de Barcelona","url":"https:\/\/www.sindicaturabarcelona.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2023\/02\/logo_sindicatura.svg","contentUrl":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2023\/02\/logo_sindicatura.svg","caption":"Sindicatura de Greuges de Barcelona"},"image":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/sindicbarcelona","https:\/\/www.instagram.com\/sindicbarcelona\/","https:\/\/www.tiktok.com\/@sindicaturabcn","https:\/\/t.me\/sindicaturabarcelona"]},{"@type":"Person","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#\/schema\/person\/0e5acffc350ffdbc97578159322c9452","name":"Pablo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g","caption":"Pablo"},"url":"https:\/\/www.sindicaturabarcelona.cat\/es\/author\/pablo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/posts\/13931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/comments?post=13931"}],"version-history":[{"count":0,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/posts\/13931\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/media\/13929"}],"wp:attachment":[{"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/media?parent=13931"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/tags?post=13931"},{"taxonomy":"drets","embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/drets?post=13931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}