{"id":12024,"date":"2020-11-02T16:47:00","date_gmt":"2020-11-02T14:47:00","guid":{"rendered":"https:\/\/www.sindicabarcelona.cat\/?p=12024"},"modified":"2021-04-12T08:19:31","modified_gmt":"2021-04-12T06:19:31","slug":"la-sindica-sigue-trasladando-al-defensor-del-pueblo-quejas-en-materia-de-extranjeria-y-reclama-a-las-administraciones-competentes-una-solucion-urgente-para-acabar-con-esta-vulneracion-de-derechos","status":"publish","type":"post","link":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-sigue-trasladando-al-defensor-del-pueblo-quejas-en-materia-de-extranjeria-y-reclama-a-las-administraciones-competentes-una-solucion-urgente-para-acabar-con-esta-vulneracion-de-derechos\/","title":{"rendered":"La s\u00edndica sigue trasladando al Defensor del Pueblo quejas en materia de extranjer\u00eda y reclama a las administraciones competentes una soluci\u00f3n urgente para acabar con esta vulneraci\u00f3n de derechos"},"content":{"rendered":"\n<p>Vil\u00e0 ha tenido constancia de pr\u00e1cticas fraudulentas en la solicitud de la&nbsp;ITE&nbsp;(tarjeta de identidad de extranjero): personas extranjeras han hecho pagos de hasta 300 euros a empresas para obtener una cita que la Administraci\u00f3n ofrece gratuitamente.<br><br><a href=\"https:\/\/sindicadegreugesbcn.cat\/pdf\/premsa\/nota_741604665119.pdf\">Nota de premsa<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vil\u00e0 ha tenido constancia de pr\u00e1cticas fraudulentas en la solicitud de la&nbsp;ITE&nbsp;(tarjeta de identidad de extranjero): personas extranjeras han hecho pagos de hasta 300 euros a empresas para obtener una [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":12022,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"tags":[],"drets":[],"class_list":["post-12024","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La s\u00edndica sigue trasladando al Defensor del Pueblo quejas en materia de extranjer\u00eda y reclama a las administraciones competentes una soluci\u00f3n urgente para acabar con esta vulneraci\u00f3n de derechos - Sindicatura de Greuges de Barcelona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-sigue-trasladando-al-defensor-del-pueblo-quejas-en-materia-de-extranjeria-y-reclama-a-las-administraciones-competentes-una-solucion-urgente-para-acabar-con-esta-vulneracion-de-derechos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La s\u00edndica sigue trasladando al Defensor del Pueblo quejas en materia de extranjer\u00eda y reclama a las administraciones competentes una soluci\u00f3n urgente para acabar con esta vulneraci\u00f3n de derechos - Sindicatura de Greuges de Barcelona\" \/>\n<meta property=\"og:description\" content=\"Vil\u00e0 ha tenido constancia de pr\u00e1cticas fraudulentas en la solicitud de la&nbsp;ITE&nbsp;(tarjeta de identidad de extranjero): personas extranjeras han hecho pagos de hasta 300 euros a empresas para obtener una [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-sigue-trasladando-al-defensor-del-pueblo-quejas-en-materia-de-extranjeria-y-reclama-a-las-administraciones-competentes-una-solucion-urgente-para-acabar-con-esta-vulneracion-de-derechos\/\" \/>\n<meta property=\"og:site_name\" content=\"Sindicatura de Greuges de Barcelona\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-02T14:47:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-12T06:19:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2021\/03\/img_821604665107.png\" \/>\n\t<meta property=\"og:image:width\" content=\"740\" \/>\n\t<meta property=\"og:image:height\" content=\"635\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Pablo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sindicbarcelona\" \/>\n<meta name=\"twitter:site\" content=\"@sindicbarcelona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pablo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindica-sigue-trasladando-al-defensor-del-pueblo-quejas-en-materia-de-extranjeria-y-reclama-a-las-administraciones-competentes-una-solucion-urgente-para-acabar-con-esta-vulneracion-de-derechos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindica-sigue-trasladando-al-defensor-del-pueblo-quejas-en-materia-de-extranjeria-y-reclama-a-las-administraciones-competentes-una-solucion-urgente-para-acabar-con-esta-vulneracion-de-derechos\\\/\"},\"author\":{\"name\":\"Pablo\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#\\\/schema\\\/person\\\/0e5acffc350ffdbc97578159322c9452\"},\"headline\":\"La s\u00edndica sigue trasladando al Defensor del Pueblo quejas en materia de extranjer\u00eda y reclama a las administraciones competentes una soluci\u00f3n urgente para acabar con esta vulneraci\u00f3n de derechos\",\"datePublished\":\"2020-11-02T14:47:00+00:00\",\"dateModified\":\"2021-04-12T06:19:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindica-sigue-trasladando-al-defensor-del-pueblo-quejas-en-materia-de-extranjeria-y-reclama-a-las-administraciones-competentes-una-solucion-urgente-para-acabar-con-esta-vulneracion-de-derechos\\\/\"},\"wordCount\":77,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindica-sigue-trasladando-al-defensor-del-pueblo-quejas-en-materia-de-extranjeria-y-reclama-a-las-administraciones-competentes-una-solucion-urgente-para-acabar-con-esta-vulneracion-de-derechos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/img_821604665107.png\",\"articleSection\":[\"Buen gobierno\",\"Seguridad y convivencia\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindica-sigue-trasladando-al-defensor-del-pueblo-quejas-en-materia-de-extranjeria-y-reclama-a-las-administraciones-competentes-una-solucion-urgente-para-acabar-con-esta-vulneracion-de-derechos\\\/\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindica-sigue-trasladando-al-defensor-del-pueblo-quejas-en-materia-de-extranjeria-y-reclama-a-las-administraciones-competentes-una-solucion-urgente-para-acabar-con-esta-vulneracion-de-derechos\\\/\",\"name\":\"La s\u00edndica sigue trasladando al Defensor del Pueblo quejas en materia de extranjer\u00eda y reclama a las administraciones competentes una soluci\u00f3n urgente para acabar con esta vulneraci\u00f3n de derechos - Sindicatura de Greuges de Barcelona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindica-sigue-trasladando-al-defensor-del-pueblo-quejas-en-materia-de-extranjeria-y-reclama-a-las-administraciones-competentes-una-solucion-urgente-para-acabar-con-esta-vulneracion-de-derechos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindica-sigue-trasladando-al-defensor-del-pueblo-quejas-en-materia-de-extranjeria-y-reclama-a-las-administraciones-competentes-una-solucion-urgente-para-acabar-con-esta-vulneracion-de-derechos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/img_821604665107.png\",\"datePublished\":\"2020-11-02T14:47:00+00:00\",\"dateModified\":\"2021-04-12T06:19:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindica-sigue-trasladando-al-defensor-del-pueblo-quejas-en-materia-de-extranjeria-y-reclama-a-las-administraciones-competentes-una-solucion-urgente-para-acabar-con-esta-vulneracion-de-derechos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindica-sigue-trasladando-al-defensor-del-pueblo-quejas-en-materia-de-extranjeria-y-reclama-a-las-administraciones-competentes-una-solucion-urgente-para-acabar-con-esta-vulneracion-de-derechos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindica-sigue-trasladando-al-defensor-del-pueblo-quejas-en-materia-de-extranjeria-y-reclama-a-las-administraciones-competentes-una-solucion-urgente-para-acabar-con-esta-vulneracion-de-derechos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/img_821604665107.png\",\"contentUrl\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/img_821604665107.png\",\"width\":740,\"height\":635},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindica-sigue-trasladando-al-defensor-del-pueblo-quejas-en-materia-de-extranjeria-y-reclama-a-las-administraciones-competentes-una-solucion-urgente-para-acabar-con-esta-vulneracion-de-derechos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La s\u00edndica sigue trasladando al Defensor del Pueblo quejas en materia de extranjer\u00eda y reclama a las administraciones competentes una soluci\u00f3n urgente para acabar con esta vulneraci\u00f3n de derechos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/\",\"name\":\"Sindicatura de Greuges de Barcelona\",\"description\":\"La defensoria dels teus drets\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#organization\",\"name\":\"Sindicatura de Greuges de Barcelona\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/logo_sindicatura.svg\",\"contentUrl\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/logo_sindicatura.svg\",\"caption\":\"Sindicatura de Greuges de Barcelona\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/sindicbarcelona\",\"https:\\\/\\\/www.instagram.com\\\/sindicbarcelona\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@sindicaturabcn\",\"https:\\\/\\\/t.me\\\/sindicaturabarcelona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#\\\/schema\\\/person\\\/0e5acffc350ffdbc97578159322c9452\",\"name\":\"Pablo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g\",\"caption\":\"Pablo\"},\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/author\\\/pablo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La s\u00edndica sigue trasladando al Defensor del Pueblo quejas en materia de extranjer\u00eda y reclama a las administraciones competentes una soluci\u00f3n urgente para acabar con esta vulneraci\u00f3n de derechos - Sindicatura de Greuges de Barcelona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-sigue-trasladando-al-defensor-del-pueblo-quejas-en-materia-de-extranjeria-y-reclama-a-las-administraciones-competentes-una-solucion-urgente-para-acabar-con-esta-vulneracion-de-derechos\/","og_locale":"es_ES","og_type":"article","og_title":"La s\u00edndica sigue trasladando al Defensor del Pueblo quejas en materia de extranjer\u00eda y reclama a las administraciones competentes una soluci\u00f3n urgente para acabar con esta vulneraci\u00f3n de derechos - Sindicatura de Greuges de Barcelona","og_description":"Vil\u00e0 ha tenido constancia de pr\u00e1cticas fraudulentas en la solicitud de la&nbsp;ITE&nbsp;(tarjeta de identidad de extranjero): personas extranjeras han hecho pagos de hasta 300 euros a empresas para obtener una [&hellip;]","og_url":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-sigue-trasladando-al-defensor-del-pueblo-quejas-en-materia-de-extranjeria-y-reclama-a-las-administraciones-competentes-una-solucion-urgente-para-acabar-con-esta-vulneracion-de-derechos\/","og_site_name":"Sindicatura de Greuges de Barcelona","article_published_time":"2020-11-02T14:47:00+00:00","article_modified_time":"2021-04-12T06:19:31+00:00","og_image":[{"width":740,"height":635,"url":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2021\/03\/img_821604665107.png","type":"image\/png"}],"author":"Pablo","twitter_card":"summary_large_image","twitter_creator":"@sindicbarcelona","twitter_site":"@sindicbarcelona","twitter_misc":{"Escrito por":"Pablo"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-sigue-trasladando-al-defensor-del-pueblo-quejas-en-materia-de-extranjeria-y-reclama-a-las-administraciones-competentes-una-solucion-urgente-para-acabar-con-esta-vulneracion-de-derechos\/#article","isPartOf":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-sigue-trasladando-al-defensor-del-pueblo-quejas-en-materia-de-extranjeria-y-reclama-a-las-administraciones-competentes-una-solucion-urgente-para-acabar-con-esta-vulneracion-de-derechos\/"},"author":{"name":"Pablo","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#\/schema\/person\/0e5acffc350ffdbc97578159322c9452"},"headline":"La s\u00edndica sigue trasladando al Defensor del Pueblo quejas en materia de extranjer\u00eda y reclama a las administraciones competentes una soluci\u00f3n urgente para acabar con esta vulneraci\u00f3n de derechos","datePublished":"2020-11-02T14:47:00+00:00","dateModified":"2021-04-12T06:19:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-sigue-trasladando-al-defensor-del-pueblo-quejas-en-materia-de-extranjeria-y-reclama-a-las-administraciones-competentes-una-solucion-urgente-para-acabar-con-esta-vulneracion-de-derechos\/"},"wordCount":77,"publisher":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#organization"},"image":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-sigue-trasladando-al-defensor-del-pueblo-quejas-en-materia-de-extranjeria-y-reclama-a-las-administraciones-competentes-una-solucion-urgente-para-acabar-con-esta-vulneracion-de-derechos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2021\/03\/img_821604665107.png","articleSection":["Buen gobierno","Seguridad y convivencia"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-sigue-trasladando-al-defensor-del-pueblo-quejas-en-materia-de-extranjeria-y-reclama-a-las-administraciones-competentes-una-solucion-urgente-para-acabar-con-esta-vulneracion-de-derechos\/","url":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-sigue-trasladando-al-defensor-del-pueblo-quejas-en-materia-de-extranjeria-y-reclama-a-las-administraciones-competentes-una-solucion-urgente-para-acabar-con-esta-vulneracion-de-derechos\/","name":"La s\u00edndica sigue trasladando al Defensor del Pueblo quejas en materia de extranjer\u00eda y reclama a las administraciones competentes una soluci\u00f3n urgente para acabar con esta vulneraci\u00f3n de derechos - Sindicatura de Greuges de Barcelona","isPartOf":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-sigue-trasladando-al-defensor-del-pueblo-quejas-en-materia-de-extranjeria-y-reclama-a-las-administraciones-competentes-una-solucion-urgente-para-acabar-con-esta-vulneracion-de-derechos\/#primaryimage"},"image":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-sigue-trasladando-al-defensor-del-pueblo-quejas-en-materia-de-extranjeria-y-reclama-a-las-administraciones-competentes-una-solucion-urgente-para-acabar-con-esta-vulneracion-de-derechos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2021\/03\/img_821604665107.png","datePublished":"2020-11-02T14:47:00+00:00","dateModified":"2021-04-12T06:19:31+00:00","breadcrumb":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-sigue-trasladando-al-defensor-del-pueblo-quejas-en-materia-de-extranjeria-y-reclama-a-las-administraciones-competentes-una-solucion-urgente-para-acabar-con-esta-vulneracion-de-derechos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-sigue-trasladando-al-defensor-del-pueblo-quejas-en-materia-de-extranjeria-y-reclama-a-las-administraciones-competentes-una-solucion-urgente-para-acabar-con-esta-vulneracion-de-derechos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-sigue-trasladando-al-defensor-del-pueblo-quejas-en-materia-de-extranjeria-y-reclama-a-las-administraciones-competentes-una-solucion-urgente-para-acabar-con-esta-vulneracion-de-derechos\/#primaryimage","url":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2021\/03\/img_821604665107.png","contentUrl":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2021\/03\/img_821604665107.png","width":740,"height":635},{"@type":"BreadcrumbList","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-sigue-trasladando-al-defensor-del-pueblo-quejas-en-materia-de-extranjeria-y-reclama-a-las-administraciones-competentes-una-solucion-urgente-para-acabar-con-esta-vulneracion-de-derechos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.sindicaturabarcelona.cat\/es\/"},{"@type":"ListItem","position":2,"name":"La s\u00edndica sigue trasladando al Defensor del Pueblo quejas en materia de extranjer\u00eda y reclama a las administraciones competentes una soluci\u00f3n urgente para acabar con esta vulneraci\u00f3n de derechos"}]},{"@type":"WebSite","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#website","url":"https:\/\/www.sindicaturabarcelona.cat\/es\/","name":"Sindicatura de Greuges de Barcelona","description":"La defensoria dels teus drets","publisher":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sindicaturabarcelona.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#organization","name":"Sindicatura de Greuges de Barcelona","url":"https:\/\/www.sindicaturabarcelona.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2023\/02\/logo_sindicatura.svg","contentUrl":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2023\/02\/logo_sindicatura.svg","caption":"Sindicatura de Greuges de Barcelona"},"image":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/sindicbarcelona","https:\/\/www.instagram.com\/sindicbarcelona\/","https:\/\/www.tiktok.com\/@sindicaturabcn","https:\/\/t.me\/sindicaturabarcelona"]},{"@type":"Person","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#\/schema\/person\/0e5acffc350ffdbc97578159322c9452","name":"Pablo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g","caption":"Pablo"},"url":"https:\/\/www.sindicaturabarcelona.cat\/es\/author\/pablo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/posts\/12024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/comments?post=12024"}],"version-history":[{"count":0,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/posts\/12024\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/media\/12022"}],"wp:attachment":[{"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/media?parent=12024"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/tags?post=12024"},{"taxonomy":"drets","embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/drets?post=12024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}