{"id":11217,"date":"2019-07-01T00:00:00","date_gmt":"2019-06-30T22:00:00","guid":{"rendered":"http:\/\/minimalweb.tech\/sindica\/2019\/07\/01\/la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro\/"},"modified":"2021-04-12T07:57:57","modified_gmt":"2021-04-12T05:57:57","slug":"la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro","status":"publish","type":"post","link":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro\/","title":{"rendered":"La S\u00edndica de Barcelona advierte de la necesidad de informar adecuadamente de los futuros cortes de las l\u00edneas 2 y 5 de metro"},"content":{"rendered":"<p>Tras el malestar de los usuarios por el corte de la L1, y en previsi\u00f3n de los futuros cortes de las l\u00edneas 2 y 5 de metro, la s\u00edndica Vil\u00e0 advierte de la necesidad de comunicar claramente las alternativas de transporte.<\/p>\n<p class=\"noti_nota\"><a href=\"https:\/\/www.sindicaturabarcelona.cat\/src\/pdf\/nota_191563449302.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Nota de prensa<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras el malestar de los usuarios por el corte de la L1, y en previsi\u00f3n de los futuros cortes de las l\u00edneas 2 y 5 de metro, la s\u00edndica Vil\u00e0 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5269,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"tags":[],"drets":[],"class_list":["post-11217","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La S\u00edndica de Barcelona advierte de la necesidad de informar adecuadamente de los futuros cortes de las l\u00edneas 2 y 5 de metro - Sindicatura de Greuges de Barcelona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La S\u00edndica de Barcelona advierte de la necesidad de informar adecuadamente de los futuros cortes de las l\u00edneas 2 y 5 de metro - Sindicatura de Greuges de Barcelona\" \/>\n<meta property=\"og:description\" content=\"Tras el malestar de los usuarios por el corte de la L1, y en previsi\u00f3n de los futuros cortes de las l\u00edneas 2 y 5 de metro, la s\u00edndica Vil\u00e0 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro\/\" \/>\n<meta property=\"og:site_name\" content=\"Sindicatura de Greuges de Barcelona\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-30T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-12T05:57:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2020\/08\/img_861563435908-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1704\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pablo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sindicbarcelona\" \/>\n<meta name=\"twitter:site\" content=\"@sindicbarcelona\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pablo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro\\\/\"},\"author\":{\"name\":\"Pablo\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#\\\/schema\\\/person\\\/0e5acffc350ffdbc97578159322c9452\"},\"headline\":\"La S\u00edndica de Barcelona advierte de la necesidad de informar adecuadamente de los futuros cortes de las l\u00edneas 2 y 5 de metro\",\"datePublished\":\"2019-06-30T22:00:00+00:00\",\"dateModified\":\"2021-04-12T05:57:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro\\\/\"},\"wordCount\":68,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/img_861563435908-scaled.jpg\",\"articleSection\":[\"Atencion comunicaci\u00f3n y participacion\",\"Buen gobierno\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro\\\/\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro\\\/\",\"name\":\"La S\u00edndica de Barcelona advierte de la necesidad de informar adecuadamente de los futuros cortes de las l\u00edneas 2 y 5 de metro - Sindicatura de Greuges de Barcelona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/img_861563435908-scaled.jpg\",\"datePublished\":\"2019-06-30T22:00:00+00:00\",\"dateModified\":\"2021-04-12T05:57:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/img_861563435908-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/img_861563435908-scaled.jpg\",\"width\":2560,\"height\":1704},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La S\u00edndica de Barcelona advierte de la necesidad de informar adecuadamente de los futuros cortes de las l\u00edneas 2 y 5 de metro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/\",\"name\":\"Sindicatura de Greuges de Barcelona\",\"description\":\"La defensoria dels teus drets\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#organization\",\"name\":\"Sindicatura de Greuges de Barcelona\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/logo_sindicatura.svg\",\"contentUrl\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/logo_sindicatura.svg\",\"caption\":\"Sindicatura de Greuges de Barcelona\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/sindicbarcelona\",\"https:\\\/\\\/www.instagram.com\\\/sindicbarcelona\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@sindicaturabcn\",\"https:\\\/\\\/t.me\\\/sindicaturabarcelona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/#\\\/schema\\\/person\\\/0e5acffc350ffdbc97578159322c9452\",\"name\":\"Pablo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g\",\"caption\":\"Pablo\"},\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/es\\\/author\\\/pablo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La S\u00edndica de Barcelona advierte de la necesidad de informar adecuadamente de los futuros cortes de las l\u00edneas 2 y 5 de metro - Sindicatura de Greuges de Barcelona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro\/","og_locale":"es_ES","og_type":"article","og_title":"La S\u00edndica de Barcelona advierte de la necesidad de informar adecuadamente de los futuros cortes de las l\u00edneas 2 y 5 de metro - Sindicatura de Greuges de Barcelona","og_description":"Tras el malestar de los usuarios por el corte de la L1, y en previsi\u00f3n de los futuros cortes de las l\u00edneas 2 y 5 de metro, la s\u00edndica Vil\u00e0 [&hellip;]","og_url":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro\/","og_site_name":"Sindicatura de Greuges de Barcelona","article_published_time":"2019-06-30T22:00:00+00:00","article_modified_time":"2021-04-12T05:57:57+00:00","og_image":[{"width":2560,"height":1704,"url":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2020\/08\/img_861563435908-scaled.jpg","type":"image\/jpeg"}],"author":"Pablo","twitter_card":"summary_large_image","twitter_creator":"@sindicbarcelona","twitter_site":"@sindicbarcelona","twitter_misc":{"Escrito por":"Pablo"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro\/#article","isPartOf":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro\/"},"author":{"name":"Pablo","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#\/schema\/person\/0e5acffc350ffdbc97578159322c9452"},"headline":"La S\u00edndica de Barcelona advierte de la necesidad de informar adecuadamente de los futuros cortes de las l\u00edneas 2 y 5 de metro","datePublished":"2019-06-30T22:00:00+00:00","dateModified":"2021-04-12T05:57:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro\/"},"wordCount":68,"publisher":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#organization"},"image":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2020\/08\/img_861563435908-scaled.jpg","articleSection":["Atencion comunicaci\u00f3n y participacion","Buen gobierno"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro\/","url":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro\/","name":"La S\u00edndica de Barcelona advierte de la necesidad de informar adecuadamente de los futuros cortes de las l\u00edneas 2 y 5 de metro - Sindicatura de Greuges de Barcelona","isPartOf":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro\/#primaryimage"},"image":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2020\/08\/img_861563435908-scaled.jpg","datePublished":"2019-06-30T22:00:00+00:00","dateModified":"2021-04-12T05:57:57+00:00","breadcrumb":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro\/#primaryimage","url":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2020\/08\/img_861563435908-scaled.jpg","contentUrl":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2020\/08\/img_861563435908-scaled.jpg","width":2560,"height":1704},{"@type":"BreadcrumbList","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/la-sindica-de-barcelona-advierte-de-la-necesidad-de-informar-adecuadamente-de-los-futuros-cortes-de-las-lineas-2-y-5-de-metro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.sindicaturabarcelona.cat\/es\/"},{"@type":"ListItem","position":2,"name":"La S\u00edndica de Barcelona advierte de la necesidad de informar adecuadamente de los futuros cortes de las l\u00edneas 2 y 5 de metro"}]},{"@type":"WebSite","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#website","url":"https:\/\/www.sindicaturabarcelona.cat\/es\/","name":"Sindicatura de Greuges de Barcelona","description":"La defensoria dels teus drets","publisher":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sindicaturabarcelona.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#organization","name":"Sindicatura de Greuges de Barcelona","url":"https:\/\/www.sindicaturabarcelona.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2023\/02\/logo_sindicatura.svg","contentUrl":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2023\/02\/logo_sindicatura.svg","caption":"Sindicatura de Greuges de Barcelona"},"image":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/sindicbarcelona","https:\/\/www.instagram.com\/sindicbarcelona\/","https:\/\/www.tiktok.com\/@sindicaturabcn","https:\/\/t.me\/sindicaturabarcelona"]},{"@type":"Person","@id":"https:\/\/www.sindicaturabarcelona.cat\/es\/#\/schema\/person\/0e5acffc350ffdbc97578159322c9452","name":"Pablo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g","caption":"Pablo"},"url":"https:\/\/www.sindicaturabarcelona.cat\/es\/author\/pablo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/posts\/11217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/comments?post=11217"}],"version-history":[{"count":0,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/posts\/11217\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/media\/5269"}],"wp:attachment":[{"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/media?parent=11217"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/tags?post=11217"},{"taxonomy":"drets","embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/es\/wp-json\/wp\/v2\/drets?post=11217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}