{"id":41330,"date":"2026-01-15T09:00:00","date_gmt":"2026-01-15T07:00:00","guid":{"rendered":"https:\/\/www.sindicaturabarcelona.cat\/?p=41330"},"modified":"2026-01-15T09:00:08","modified_gmt":"2026-01-15T07:00:08","slug":"sindicatura-greuges-barcelona-ajuntament-acollida-fira-joc-casinos-apostes","status":"publish","type":"post","link":"https:\/\/www.sindicaturabarcelona.cat\/en\/sindicatura-greuges-barcelona-ajuntament-acollida-fira-joc-casinos-apostes\/","title":{"rendered":"La Sindicatura de Greuges de Barcelona torna a instar l\u2019Ajuntament a reconsiderar l\u2019acollida de la fira del joc"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><strong>La defensoria insisteix als representants municipals que debatin sobre la conveni\u00e8ncia de la celebraci\u00f3 de la fira del joc, casinos i apostes, que se celebrar\u00e0 per segon cop a la ciutat del 19 al 21 de gener a Fira de Barcelona<\/strong><\/li>\n\n\n\n<li><strong>Considera que el consistori es contradiu desplegant pol\u00edtiques per combatre l<\/strong>\u2019<strong>addicci\u00f3 i alhora cofinan\u00e7ant l<\/strong>\u2019<strong>esdeveniment mundial m\u00e9s gran dirigit a professionals del joc; per aix\u00f2 recomana que s<\/strong>\u2019<strong>inici\u00efn les negociacions per cancel\u00b7lar el contracte, vigent fins al 2029<\/strong><\/li>\n<\/ul>\n\n\n\n<p>La Sindicatura de Greuges de Barcelona torna a recomanar als representants municipals de l\u2019Ajuntament que <strong>debatin sobre la conveni\u00e8ncia<\/strong> de celebrar la <a href=\"https:\/\/www.icegaming.com\/\">fira del joc, casinos i apostes<\/a>&nbsp; (anomenada ICE and IGB Affiliate), que se celebra per segon any consecutiu a la Fira de Barcelona del <strong>19 al 21 de gener<\/strong>, i que est\u00e0 previst que continu\u00ef celebrant-se 2029, despr\u00e9s que la Fira sign\u00e9s un contracte de cinc anys.<\/p>\n\n\n\n<p>Va ser el mes de mar\u00e7 de 2024 quan la Sindicatura va iniciar una <a href=\"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/202410_Dret-salut_AO-sobre-la-celebracio-de-la-Fira-del-Joc-Casinos-i-Apostes_24OF000005.pdf\"><strong>actuaci\u00f3 d\u2019ofici<\/strong><\/a> despr\u00e9s de tenir coneixement que Barcelona acolliria aquest esdeveniment. La defensoria la va resoldre manifestant la seva <strong>preocupaci\u00f3 per la discrep\u00e0ncia entre les l\u00ednies estrat\u00e8giques de l\u2019Ajuntament en mat\u00e8ria de salut i la decisi\u00f3 de la Fira d\u2019acollir un esdeveniment internacional dedicat al joc, els casinos i les apostes<\/strong>.<\/p>\n\n\n\n<p>Davant de la nova celebraci\u00f3 de l\u2019esdeveniment, la defensoria torna a recomanar <strong>als representants municipals de l\u2019Ajuntament a la Fira de Barcelona<\/strong> que abordin el debat sobre la celebraci\u00f3, i, si s\u2019escau, que <strong>inici\u00efn les negociacions per a la cancel\u00b7laci\u00f3 o resoluci\u00f3 anticipada del contracte<\/strong> amb l\u2019organitzador.&nbsp;<\/p>\n\n\n\n<p><strong>Un apartat de prevenci\u00f3 i zero difusi\u00f3<\/strong><\/p>\n\n\n\n<p>En cas que no es pogu\u00e9s cancel\u00b7lar anticipadament, la Sindicatura <strong>proposa que en la trobada hi hagi un apartat de prevenci\u00f3 i protecci\u00f3 <\/strong>adre\u00e7at a les persones consumidores, aix\u00ed com que <strong>no es faci difusi\u00f3 de l\u2019esdeveniment a la via p\u00fablica<\/strong>.<\/p>\n\n\n\n<p>Per a la Sindicatura representa una <strong>contradicci\u00f3 evident<\/strong> que el consistori desplegui una s\u00f2lida pol\u00edtica per combatre l\u2019addicci\u00f3 al joc -reducci\u00f3 del nombre d\u2019establiments, l\u00edmits publicitaris, programes de prevenci\u00f3- per\u00f2, alhora aculli l\u2019esdeveniment mundial m\u00e9s gran dirigit a professionals del joc, casinos i apostes.<\/p>\n\n\n\n<p><strong>La representaci\u00f3 de l\u2019Ajuntament a la Fira de Barcelona<\/strong><\/p>\n\n\n\n<p>La Fira de Barcelona \u00e9s una entitat de naturalesa p\u00fablica, de base associativa i de car\u00e0cter consorcial,&nbsp;<strong>integrada de manera igualit\u00e0ria per l\u2019Ajuntament de Barcelona, la Generalitat de Catalunya i la Cambra Oficial de Comer\u00e7, Ind\u00fastria i Navegaci\u00f3<\/strong> de Barcelona, amb els mateixos drets i obligacions.<\/p>\n\n\n\n<p>En l\u2019an\u00e0lisi duta a terme per la Sindicatura, s\u2019ha copsat que el sistema de governan\u00e7a de la Fira inclou tres nivells diferenciats per a la presa de decisions: Consell General, Consell d\u2019Administraci\u00f3 i la Direcci\u00f3 General.&nbsp;<strong>L\u2019Ajuntament de Barcelona est\u00e0 representat en el Consell General<\/strong>.<\/p>\n\n\n\n<p>Segons els articles 15 i 22 dels estatuts d\u2019aquest organisme, correspon al Consell d\u2019Administraci\u00f3 programar i organitzar les activitats firals. Per\u00f2 concretament en l\u2019article 8, s\u2019assigna al <strong>Consell General la compet\u00e8ncia de fixar les l\u00ednies generals d\u2019actuaci\u00f3 de la Fira<\/strong>, i tamb\u00e9 l\u2019aprovaci\u00f3 anual dels plans estrat\u00e8gics d\u2019actuaci\u00f3.<\/p>\n\n\n\n<p>Tenint aquest context del funcionament de la&nbsp;<a href=\"https:\/\/www.firabarcelona.com\/\">Fira de Barcelona<\/a>,&nbsp;la Sindicatura de Greuges considera que <strong>l\u2019Ajuntament disposa d\u2019eines institucionals i jur\u00eddiques per evitar contradiccions com la que suposa allotjar aquesta trobada<\/strong>.<\/p>\n\n\n\n<p>&#8220;\u00c9s necessari que <strong>els valors que defensa l\u2019Ajuntament de Barcelona impregnin totes les accions de govern i totes les institucions<\/strong> en qu\u00e8 participa. En particular a la Fira, cal que actu\u00ef de manera coherent amb aquests principis per fer front a una problem\u00e0tica social com s\u00f3n les addiccions als jocs i l\u2019aposta\u201d, argumenta el s\u00edndic de greuges de Barcelona, <strong>David Bondia<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Sindicatura de Greuges de Barcelona torna a recomanar als representants municipals de l\u2019Ajuntament que debatin sobre la conveni\u00e8ncia de celebrar la fira del joc, casinos i apostes&nbsp; (anomenada ICE [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":41339,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"tags":[],"drets":[1599,1620],"class_list":["post-41330","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","drets-right-to-health","drets-right-to-good-administration"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Sindicatura de Greuges de Barcelona torna a instar l\u2019Ajuntament a reconsiderar l\u2019acollida de la fira del joc - Sindicatura de Greuges de Barcelona<\/title>\n<meta name=\"description\" content=\"Insisteix en la necessitat d&#039;un debat sobre la conveni\u00e8ncia d&#039;un esdeveniment contrari a les pol\u00edtiques de salut impulsades pel consistori\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sindicaturabarcelona.cat\/en\/sindicatura-greuges-barcelona-ajuntament-acollida-fira-joc-casinos-apostes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Sindicatura de Greuges de Barcelona torna a instar l\u2019Ajuntament a reconsiderar l\u2019acollida de la fira del joc - Sindicatura de Greuges de Barcelona\" \/>\n<meta property=\"og:description\" content=\"Insisteix en la necessitat d&#039;un debat sobre la conveni\u00e8ncia d&#039;un esdeveniment contrari a les pol\u00edtiques de salut impulsades pel consistori\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sindicaturabarcelona.cat\/en\/sindicatura-greuges-barcelona-ajuntament-acollida-fira-joc-casinos-apostes\/\" \/>\n<meta property=\"og:site_name\" content=\"Sindicatura de Greuges de Barcelona\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-15T07:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-15T07:00:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/ruleta.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pablo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sindicbarcelona\" \/>\n<meta name=\"twitter:site\" content=\"@sindicbarcelona\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pablo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/en\\\/sindicatura-greuges-barcelona-ajuntament-acollida-fira-joc-casinos-apostes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/en\\\/sindicatura-greuges-barcelona-ajuntament-acollida-fira-joc-casinos-apostes\\\/\"},\"author\":{\"name\":\"Pablo\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/en\\\/#\\\/schema\\\/person\\\/0e5acffc350ffdbc97578159322c9452\"},\"headline\":\"La Sindicatura de Greuges de Barcelona torna a instar l\u2019Ajuntament a reconsiderar l\u2019acollida de la fira del joc\",\"datePublished\":\"2026-01-15T07:00:00+00:00\",\"dateModified\":\"2026-01-15T07:00:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/en\\\/sindicatura-greuges-barcelona-ajuntament-acollida-fira-joc-casinos-apostes\\\/\"},\"wordCount\":679,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/en\\\/sindicatura-greuges-barcelona-ajuntament-acollida-fira-joc-casinos-apostes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/ruleta.jpg\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/en\\\/sindicatura-greuges-barcelona-ajuntament-acollida-fira-joc-casinos-apostes\\\/\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/en\\\/sindicatura-greuges-barcelona-ajuntament-acollida-fira-joc-casinos-apostes\\\/\",\"name\":\"La Sindicatura de Greuges de Barcelona torna a instar l\u2019Ajuntament a reconsiderar l\u2019acollida de la fira del joc - Sindicatura de Greuges de Barcelona\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/en\\\/sindicatura-greuges-barcelona-ajuntament-acollida-fira-joc-casinos-apostes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/en\\\/sindicatura-greuges-barcelona-ajuntament-acollida-fira-joc-casinos-apostes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/ruleta.jpg\",\"datePublished\":\"2026-01-15T07:00:00+00:00\",\"dateModified\":\"2026-01-15T07:00:08+00:00\",\"description\":\"Insisteix en la necessitat d'un debat sobre la conveni\u00e8ncia d'un esdeveniment contrari a les pol\u00edtiques de salut impulsades pel consistori\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/en\\\/sindicatura-greuges-barcelona-ajuntament-acollida-fira-joc-casinos-apostes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/en\\\/sindicatura-greuges-barcelona-ajuntament-acollida-fira-joc-casinos-apostes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/en\\\/sindicatura-greuges-barcelona-ajuntament-acollida-fira-joc-casinos-apostes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/ruleta.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/ruleta.jpg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/en\\\/sindicatura-greuges-barcelona-ajuntament-acollida-fira-joc-casinos-apostes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Sindicatura de Greuges de Barcelona torna a instar l\u2019Ajuntament a reconsiderar l\u2019acollida de la fira del joc\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/en\\\/\",\"name\":\"Sindicatura de Greuges de Barcelona\",\"description\":\"La defensoria dels teus drets\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/en\\\/#organization\",\"name\":\"Sindicatura de Greuges de Barcelona\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/logo_sindicatura.svg\",\"contentUrl\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/logo_sindicatura.svg\",\"caption\":\"Sindicatura de Greuges de Barcelona\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/sindicbarcelona\",\"https:\\\/\\\/www.instagram.com\\\/sindicbarcelona\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@sindicaturabcn\",\"https:\\\/\\\/t.me\\\/sindicaturabarcelona\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/en\\\/#\\\/schema\\\/person\\\/0e5acffc350ffdbc97578159322c9452\",\"name\":\"Pablo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g\",\"caption\":\"Pablo\"},\"url\":\"https:\\\/\\\/www.sindicaturabarcelona.cat\\\/en\\\/author\\\/pablo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Sindicatura de Greuges de Barcelona torna a instar l\u2019Ajuntament a reconsiderar l\u2019acollida de la fira del joc - Sindicatura de Greuges de Barcelona","description":"Insisteix en la necessitat d'un debat sobre la conveni\u00e8ncia d'un esdeveniment contrari a les pol\u00edtiques de salut impulsades pel consistori","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sindicaturabarcelona.cat\/en\/sindicatura-greuges-barcelona-ajuntament-acollida-fira-joc-casinos-apostes\/","og_locale":"en_US","og_type":"article","og_title":"La Sindicatura de Greuges de Barcelona torna a instar l\u2019Ajuntament a reconsiderar l\u2019acollida de la fira del joc - Sindicatura de Greuges de Barcelona","og_description":"Insisteix en la necessitat d'un debat sobre la conveni\u00e8ncia d'un esdeveniment contrari a les pol\u00edtiques de salut impulsades pel consistori","og_url":"https:\/\/www.sindicaturabarcelona.cat\/en\/sindicatura-greuges-barcelona-ajuntament-acollida-fira-joc-casinos-apostes\/","og_site_name":"Sindicatura de Greuges de Barcelona","article_published_time":"2026-01-15T07:00:00+00:00","article_modified_time":"2026-01-15T07:00:08+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/ruleta.jpg","type":"image\/jpeg"}],"author":"Pablo","twitter_card":"summary_large_image","twitter_creator":"@sindicbarcelona","twitter_site":"@sindicbarcelona","twitter_misc":{"Written by":"Pablo","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sindicaturabarcelona.cat\/en\/sindicatura-greuges-barcelona-ajuntament-acollida-fira-joc-casinos-apostes\/#article","isPartOf":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/en\/sindicatura-greuges-barcelona-ajuntament-acollida-fira-joc-casinos-apostes\/"},"author":{"name":"Pablo","@id":"https:\/\/www.sindicaturabarcelona.cat\/en\/#\/schema\/person\/0e5acffc350ffdbc97578159322c9452"},"headline":"La Sindicatura de Greuges de Barcelona torna a instar l\u2019Ajuntament a reconsiderar l\u2019acollida de la fira del joc","datePublished":"2026-01-15T07:00:00+00:00","dateModified":"2026-01-15T07:00:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/en\/sindicatura-greuges-barcelona-ajuntament-acollida-fira-joc-casinos-apostes\/"},"wordCount":679,"publisher":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/en\/#organization"},"image":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/en\/sindicatura-greuges-barcelona-ajuntament-acollida-fira-joc-casinos-apostes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/ruleta.jpg","inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.sindicaturabarcelona.cat\/en\/sindicatura-greuges-barcelona-ajuntament-acollida-fira-joc-casinos-apostes\/","url":"https:\/\/www.sindicaturabarcelona.cat\/en\/sindicatura-greuges-barcelona-ajuntament-acollida-fira-joc-casinos-apostes\/","name":"La Sindicatura de Greuges de Barcelona torna a instar l\u2019Ajuntament a reconsiderar l\u2019acollida de la fira del joc - Sindicatura de Greuges de Barcelona","isPartOf":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/en\/sindicatura-greuges-barcelona-ajuntament-acollida-fira-joc-casinos-apostes\/#primaryimage"},"image":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/en\/sindicatura-greuges-barcelona-ajuntament-acollida-fira-joc-casinos-apostes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/ruleta.jpg","datePublished":"2026-01-15T07:00:00+00:00","dateModified":"2026-01-15T07:00:08+00:00","description":"Insisteix en la necessitat d'un debat sobre la conveni\u00e8ncia d'un esdeveniment contrari a les pol\u00edtiques de salut impulsades pel consistori","breadcrumb":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/en\/sindicatura-greuges-barcelona-ajuntament-acollida-fira-joc-casinos-apostes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sindicaturabarcelona.cat\/en\/sindicatura-greuges-barcelona-ajuntament-acollida-fira-joc-casinos-apostes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.sindicaturabarcelona.cat\/en\/sindicatura-greuges-barcelona-ajuntament-acollida-fira-joc-casinos-apostes\/#primaryimage","url":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/ruleta.jpg","contentUrl":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/ruleta.jpg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/www.sindicaturabarcelona.cat\/en\/sindicatura-greuges-barcelona-ajuntament-acollida-fira-joc-casinos-apostes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.sindicaturabarcelona.cat\/en\/"},{"@type":"ListItem","position":2,"name":"La Sindicatura de Greuges de Barcelona torna a instar l\u2019Ajuntament a reconsiderar l\u2019acollida de la fira del joc"}]},{"@type":"WebSite","@id":"https:\/\/www.sindicaturabarcelona.cat\/en\/#website","url":"https:\/\/www.sindicaturabarcelona.cat\/en\/","name":"Sindicatura de Greuges de Barcelona","description":"La defensoria dels teus drets","publisher":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sindicaturabarcelona.cat\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.sindicaturabarcelona.cat\/en\/#organization","name":"Sindicatura de Greuges de Barcelona","url":"https:\/\/www.sindicaturabarcelona.cat\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.sindicaturabarcelona.cat\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2023\/02\/logo_sindicatura.svg","contentUrl":"https:\/\/www.sindicaturabarcelona.cat\/wp-content\/uploads\/2023\/02\/logo_sindicatura.svg","caption":"Sindicatura de Greuges de Barcelona"},"image":{"@id":"https:\/\/www.sindicaturabarcelona.cat\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/sindicbarcelona","https:\/\/www.instagram.com\/sindicbarcelona\/","https:\/\/www.tiktok.com\/@sindicaturabcn","https:\/\/t.me\/sindicaturabarcelona"]},{"@type":"Person","@id":"https:\/\/www.sindicaturabarcelona.cat\/en\/#\/schema\/person\/0e5acffc350ffdbc97578159322c9452","name":"Pablo","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c948169b402ef9492afde705c3dfd5e90e1a6a84ef6840a91124f805a25a480f?s=96&d=mm&r=g","caption":"Pablo"},"url":"https:\/\/www.sindicaturabarcelona.cat\/en\/author\/pablo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.sindicaturabarcelona.cat\/en\/wp-json\/wp\/v2\/posts\/41330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sindicaturabarcelona.cat\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sindicaturabarcelona.cat\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/en\/wp-json\/wp\/v2\/comments?post=41330"}],"version-history":[{"count":2,"href":"https:\/\/www.sindicaturabarcelona.cat\/en\/wp-json\/wp\/v2\/posts\/41330\/revisions"}],"predecessor-version":[{"id":41334,"href":"https:\/\/www.sindicaturabarcelona.cat\/en\/wp-json\/wp\/v2\/posts\/41330\/revisions\/41334"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/en\/wp-json\/wp\/v2\/media\/41339"}],"wp:attachment":[{"href":"https:\/\/www.sindicaturabarcelona.cat\/en\/wp-json\/wp\/v2\/media?parent=41330"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/en\/wp-json\/wp\/v2\/tags?post=41330"},{"taxonomy":"drets","embeddable":true,"href":"https:\/\/www.sindicaturabarcelona.cat\/en\/wp-json\/wp\/v2\/drets?post=41330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}